!function(e){var t={};function o(i){if(t[i])return t[i].exports;var r=t[i]={i:i,l:!1,exports:{}};return e[i].call(r.exports,r,r.exports,o),r.l=!0,r.exports}o.m=e,o.c=t,o.d=function(e,t,i){o.o(e,t)||Object.defineProperty(e,t,{enumerable:!0,get:i})},o.r=function(e){"undefined"!=typeof Symbol&&Symbol.toStringTag&&Object.defineProperty(e,Symbol.toStringTag,{value:"Module"}),Object.defineProperty(e,"__esModule",{value:!0})},o.t=function(e,t){if(1&t&&(e=o(e)),8&t)return e;if(4&t&&"object"==typeof e&&e&&e.__esModule)return e;var i=Object.create(null);if(o.r(i),Object.defineProperty(i,"default",{enumerable:!0,value:e}),2&t&&"string"!=typeof e)for(var r in e)o.d(i,r,function(t){return e[t]}.bind(null,r));return i},o.n=function(e){var t=e&&e.__esModule?function(){return e.default}:function(){return e};return o.d(t,"a",t),t},o.o=function(e,t){return Object.prototype.hasOwnProperty.call(e,t)},o.p="",o(o.s=8)}([function(e,t){e.exports=window.wp.data},function(e,t){e.exports=window.wp.element},function(e,t){e.exports=window.wp.components},function(e,t){e.exports=window.wp.i18n},function(e,t,o){"use strict";Object.defineProperty(t,"__esModule",{value:!0}),t.redirectOnSaveCompletion=void 0;var i=o(0),r=function(e){var t=(0,i.select)("core/editor").getCurrentPostAttribute("status"),o=(0,i.select)("core/editor").getEditedPostAttribute("status");"dp-rewrite-republish"===t&&"publish"===o&&(0,i.dispatch)("core/editor").editPost({status:t}),window.location.assign(e)};t.redirectOnSaveCompletion=function(e,t){var o=(0,i.select)("core/editor").isSavingPost(),n=(0,i.select)("core/editor").isAutosavingPost(),s=(0,i.select)("core/edit-post").hasMetaBoxes(),a=(0,i.select)("core/edit-post").isSavingMetaBoxes();return s&&!a&&t.wasSavingMetaboxes&&r(e),s||o||!t.wasSavingPost||t.wasAutoSavingPost||r(e),{isSavingPost:o,isSavingMetaBoxes:a,isAutosavingPost:n}}},,,,function(e,t,o){"use strict";var i=o(1),r=o(2),n=o(3),s=o(0),a=o(4);var u,l,c,p=function(){(0,s.dispatch)("core/editor").savePost();var e=!1,t=!1,o=!1;(0,s.subscribe)((function(){var i=(0,a.redirectOnSaveCompletion)(duplicatePostStrings.checkLink,{wasSavingPost:e,wasSavingMetaboxes:t,wasAutoSavingPost:o});e=i.isSavingPost,t=i.isSavingMetaBoxes,o=i.isAutosavingPost}))},d={Publish:(0,n.__)("Republish","duplicate-post"),"Publish:":(0,n.__)("Republish:","duplicate-post"),"Publish on:":(0,n.__)("Republish on:","duplicate-post"),"Are you ready to publish?":(0,n.__)("Are you ready to republish your post?","duplicate-post"),"Double-check your settings before publishing.":(0,i.createInterpolateElement)((0,n.__)("After republishing your changes will be merged into the original post and you'll be redirected there.<br /><br />Do you want to compare your changes with the original version before merging?<br /><br /><button>Save changes and compare</button>","duplicate-post"),{button:wp.element.createElement(r.Button,{isSecondary:!0,onClick:p}),br:wp.element.createElement("br",null)}),Schedule:(0,n.__)("Schedule republish","duplicate-post"),"Schedule…":(0,n.__)("Schedule republish…","duplicate-post"),"post action/button labelSchedule":(0,n.__)("Schedule republish","duplicate-post"),"Are you ready to schedule?":(0,n.__)("Are you ready to schedule the republishing of your post?","duplicate-post"),"Your work will be published at the specified date and time.":(0,i.createInterpolateElement)((0,n.__)("You're about to replace the original with this rewritten post at the specified date and time.<br /><br />Do you want to compare your changes with the original version before merging?<br /><br /><button>Save changes and compare</button>","duplicate-post"),{button:wp.element.createElement(r.Button,{isSecondary:!0,onClick:p}),br:wp.element.createElement("br",null)}),"is now scheduled. It will go live on":(0,n.__)(", the rewritten post, is now scheduled to replace the original post. It will be published on","duplicate-post")};for(var b in d)(0,n.setLocaleData)((c=[d[b],"duplicate-post"],(l=b)in(u={})?Object.defineProperty(u,l,{value:c,enumerable:!0,configurable:!0,writable:!0}):u[l]=c,u))}]);{"id":44328,"date":"2024-02-12T11:41:03","date_gmt":"2024-02-12T16:41:03","guid":{"rendered":"https:\/\/www.premrawat.com\/il-2023-di-prem-rawat-in-rassegna\/"},"modified":"2024-02-10T08:00:22","modified_gmt":"2024-02-10T13:00:22","slug":"il-2023-di-prem-rawat-in-rassegna","status":"publish","type":"post","link":"https:\/\/staging.premrawat.com\/it\/il-2023-di-prem-rawat-in-rassegna\/","title":{"rendered":"Il 2023 di Prem Rawat in rassegna"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_padding=&#8221;2px|||||&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;20px&#8221; text_line_height=&#8221;1.4em&#8221; link_text_color=&#8221;#1565b7&#8243; custom_margin=&#8221;30px||||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h3>Continuing his 2023 world tour (i.e., Europe, North America, Australia, Canada, and Africa), <a href=\"https:\/\/staging.premrawat.com\/it\/chi-e-prem-rawat\/\">Prem Rawat<\/a> recently completed a much-appreciated 26-day tour of India, his country of origin.<\/h3>\n<p>It began on November 8 with a Hans Jayanti event at the <a href=\"https:\/\/www.rajvidyakender.org\/about-rvk\">Raj Vidya<\/a> venue in Delhi in celebration of his father\u2019s birth. More than 2,000 people attended in person and another 8,000 from 76 countries via livestream.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;20px&#8221; text_line_height=&#8221;1.4em&#8221; link_text_color=&#8221;#1565b7&#8243; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;20px||0px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p>Il 2023 \u00e8 stato un anno di straordinaria attivit\u00e0 per <a href=\"https:\/\/staging.premrawat.com\/it\/chi-e-prem-rawat\/\">Prem Rawat<\/a> e il suo incessante impegno di far sapere a tutti che la pace non solo \u00e8 possibile, ma \u00e8 a disposizione di ogni individuo.<\/p>\n<p>Nel corso dell\u2019anno, ha percorso pi\u00f9 di 74.000 miglia nautiche, \u00e8 stato in 36 citt\u00e0 in 18 paesi e, in gran parte grazie al sostegno del Fondo Eventi di <a href=\"https:\/\/www.wopg.org\/it\/\">Words of Peace Global<\/a>, \u00e8 stato l\u2019oratore principale di 77 incontri diversi, inclusi gli eventi e le interviste con i media. Il pubblico presente dal vivo ai suoi eventi \u00e8 stato di oltre 766.000 persone, con altre 185.925 partecipanti via livestream.<\/p>\n<p>La rivoluzionaria serie di 11 sessioni di approfondimento Understanding More\u2122 in Europa, Nord America, Australia e India ha dato ispirazione, guida e supporto a oltre 39.000 persone che praticano le tecniche della <a href=\"https:\/\/staging.premrawat.com\/it\/conoscenza-del-se\/\">Conoscenza del S\u00e9<\/a>.<\/p>\n<p>Inoltre, ha stabilito due record mondiali. Il primo, il 13 aprile a <a href=\"https:\/\/staging.premrawat.com\/it\/il-lancio-del-libro-impara-ad-ascoltarti-dellautore-di-bestseller-prem-rawat-stabilisce-un-nuovo-record-mondiale-nel-guinness-dei-primati\/\">Lucknow, in India<\/a>, \u00e8 stato il primato mondiale per il maggior numero di ascoltatori presenti alla lettura di un libro di un singolo autore: 114.704. Il secondo, il 26 novembre a\u00a0 <a href=\"https:\/\/staging.premrawat.com\/it\/prem-rawat-stabilisce-un-nuovo-record-da-guinness-dei-primati-375-603-persone-partecipano-a-una-sua-conferenza-in-india\/\">Gaya, in India<\/a>, ha stabilito il record per il maggior numero di persone presenti a una conferenza: 375.603.<\/p>\n<p>Altri momenti salienti del 2023 sono stati una serie di eventi con l\u2019autore di <a href=\"https:\/\/imparaadascoltarti.it\/impara-ad-ascoltarti\/\">Impara ad ascoltarti<\/a>, interviste sui media e incontri con le persone partecipanti al suo <a href=\"https:\/\/tprf.org\/it\/programma-di-educazione-alla-pace\/\">Programma di Educazione alla Pace<\/a>.<\/p>\n<p>Con il sostegno della Fondazione Prem Rawat (TPRF), nel 2023 pi\u00f9 di 111.116 persone hanno potuto partecipare al <a href=\"https:\/\/tprf.org\/it\/programma-di-educazione-alla-pace\/\">Programma di Educazione alla Pace<\/a>, portando il totale a oltre 405.000 persone in pi\u00f9 di 80 paesi. Prem Rawat ha anche collaborato con TPRF per fornire quest\u2019anno oltre 800.000 pasti nutrienti a bambini svantaggiati tramite il programma <a href=\"https:\/\/tprf.org\/it\/food-for-people\/\">Food for People<\/a>, portando cos\u00ec il totale a oltre 5,6 milioni di pasti. Le sue attivit\u00e0 umanitarie per mezzo di TPRF hanno incluso anche la fornitura di alimentari, riparo, cure mediche e altre risorse di prima necessit\u00e0 alle vittime dei terremoti in <a href=\"https:\/\/tprf.org\/it\/la-fondazione-prem-rawat-manda-aiuti-umanitari-alle-vittime-del-terremoto-in-marocco\/\">Marocco<\/a>, <a href=\"https:\/\/tprf.org\/it\/la-fondazione-prem-rawat-dona-375-000-dollari-per-le-vittime-del-terremoto\/\">Turchia e Siria<\/a>.<\/p>\n<p>Le iscrizioni al <a href=\"https:\/\/www.youtube.com\/premrawatofficial\">canale ufficiale di Prem Rawat su YouTube<\/a> sono aumentate del 282%, pi\u00f9 di 488.000. Il suo libro campione di vendite <a href=\"https:\/\/imparaadascoltarti.it\/impara-ad-ascoltarti\/\">Impara ad ascoltarti<\/a> \u00e8 stato tradotto in altre sei lingue: greco, arabo, tedesco, hindi, ungherese, sloveno, albanese, e presto anche in tamil, per un totale, ad oggi, di 14 lingue.<\/p>\n<p>Durante l\u2019anno, 24.538 persone hanno appreso le tecniche della Conoscenza del S\u00e9, e altre 63.775 hanno partecipato alle Revisioni di Conoscenza, sessioni di ripasso per le persone che praticano queste tecniche per provare la pace personale.<\/p>\n<p>Il numero totale di persone che hanno appreso le tecniche della Conoscenza del S\u00e9 dal 1971 \u00e8 ora di oltre 1,5 milioni.<\/p>\n<p><strong>Per ulteriori dettagli e collegamenti a video e articoli di notizie correlati, fare clic sulle icone della mappa di seguito.<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 2023 \u00e8 stato un anno di straordinaria attivit\u00e0 per Prem Rawat e il suo incessante impegno di far sapere a tutti che la pace non solo \u00e8 possibile, ma \u00e8 a disposizione di ogni  individuo. <\/p>\n","protected":false},"author":18,"featured_media":43931,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[4007,4115],"tags":[4253],"podcast-category":[],"class_list":["post-44328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conoscenza-del-se","category-eventi-it","tag-prem-rawat-it"],"acf":[],"_links":{"self":[{"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/posts\/44328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/comments?post=44328"}],"version-history":[{"count":12,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/posts\/44328\/revisions"}],"predecessor-version":[{"id":44537,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/posts\/44328\/revisions\/44537"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/media\/43931"}],"wp:attachment":[{"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/media?parent=44328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/categories?post=44328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/tags?post=44328"},{"taxonomy":"podcast-category","embeddable":true,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/podcast-category?post=44328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}