!function(e){var t={};function o(i){if(t[i])return t[i].exports;var r=t[i]={i:i,l:!1,exports:{}};return e[i].call(r.exports,r,r.exports,o),r.l=!0,r.exports}o.m=e,o.c=t,o.d=function(e,t,i){o.o(e,t)||Object.defineProperty(e,t,{enumerable:!0,get:i})},o.r=function(e){"undefined"!=typeof Symbol&&Symbol.toStringTag&&Object.defineProperty(e,Symbol.toStringTag,{value:"Module"}),Object.defineProperty(e,"__esModule",{value:!0})},o.t=function(e,t){if(1&t&&(e=o(e)),8&t)return e;if(4&t&&"object"==typeof e&&e&&e.__esModule)return e;var i=Object.create(null);if(o.r(i),Object.defineProperty(i,"default",{enumerable:!0,value:e}),2&t&&"string"!=typeof e)for(var r in e)o.d(i,r,function(t){return e[t]}.bind(null,r));return i},o.n=function(e){var t=e&&e.__esModule?function(){return e.default}:function(){return e};return o.d(t,"a",t),t},o.o=function(e,t){return Object.prototype.hasOwnProperty.call(e,t)},o.p="",o(o.s=8)}([function(e,t){e.exports=window.wp.data},function(e,t){e.exports=window.wp.element},function(e,t){e.exports=window.wp.components},function(e,t){e.exports=window.wp.i18n},function(e,t,o){"use strict";Object.defineProperty(t,"__esModule",{value:!0}),t.redirectOnSaveCompletion=void 0;var i=o(0),r=function(e){var t=(0,i.select)("core/editor").getCurrentPostAttribute("status"),o=(0,i.select)("core/editor").getEditedPostAttribute("status");"dp-rewrite-republish"===t&&"publish"===o&&(0,i.dispatch)("core/editor").editPost({status:t}),window.location.assign(e)};t.redirectOnSaveCompletion=function(e,t){var o=(0,i.select)("core/editor").isSavingPost(),n=(0,i.select)("core/editor").isAutosavingPost(),s=(0,i.select)("core/edit-post").hasMetaBoxes(),a=(0,i.select)("core/edit-post").isSavingMetaBoxes();return s&&!a&&t.wasSavingMetaboxes&&r(e),s||o||!t.wasSavingPost||t.wasAutoSavingPost||r(e),{isSavingPost:o,isSavingMetaBoxes:a,isAutosavingPost:n}}},,,,function(e,t,o){"use strict";var i=o(1),r=o(2),n=o(3),s=o(0),a=o(4);var u,l,c,p=function(){(0,s.dispatch)("core/editor").savePost();var e=!1,t=!1,o=!1;(0,s.subscribe)((function(){var i=(0,a.redirectOnSaveCompletion)(duplicatePostStrings.checkLink,{wasSavingPost:e,wasSavingMetaboxes:t,wasAutoSavingPost:o});e=i.isSavingPost,t=i.isSavingMetaBoxes,o=i.isAutosavingPost}))},d={Publish:(0,n.__)("Republish","duplicate-post"),"Publish:":(0,n.__)("Republish:","duplicate-post"),"Publish on:":(0,n.__)("Republish on:","duplicate-post"),"Are you ready to publish?":(0,n.__)("Are you ready to republish your post?","duplicate-post"),"Double-check your settings before publishing.":(0,i.createInterpolateElement)((0,n.__)("After republishing your changes will be merged into the original post and you'll be redirected there.<br /><br />Do you want to compare your changes with the original version before merging?<br /><br /><button>Save changes and compare</button>","duplicate-post"),{button:wp.element.createElement(r.Button,{isSecondary:!0,onClick:p}),br:wp.element.createElement("br",null)}),Schedule:(0,n.__)("Schedule republish","duplicate-post"),"Schedule…":(0,n.__)("Schedule republish…","duplicate-post"),"post action/button labelSchedule":(0,n.__)("Schedule republish","duplicate-post"),"Are you ready to schedule?":(0,n.__)("Are you ready to schedule the republishing of your post?","duplicate-post"),"Your work will be published at the specified date and time.":(0,i.createInterpolateElement)((0,n.__)("You're about to replace the original with this rewritten post at the specified date and time.<br /><br />Do you want to compare your changes with the original version before merging?<br /><br /><button>Save changes and compare</button>","duplicate-post"),{button:wp.element.createElement(r.Button,{isSecondary:!0,onClick:p}),br:wp.element.createElement("br",null)}),"is now scheduled. It will go live on":(0,n.__)(", the rewritten post, is now scheduled to replace the original post. It will be published on","duplicate-post")};for(var b in d)(0,n.setLocaleData)((c=[d[b],"duplicate-post"],(l=b)in(u={})?Object.defineProperty(u,l,{value:c,enumerable:!0,configurable:!0,writable:!0}):u[l]=c,u))}]);{"id":40902,"date":"2023-08-30T05:02:00","date_gmt":"2023-08-30T09:02:00","guid":{"rendered":"https:\/\/www.premrawat.com\/giornata-mondiale-di-educazione-alla-pace\/"},"modified":"2023-09-27T12:41:40","modified_gmt":"2023-09-27T16:41:40","slug":"giornata-mondiale-di-educazione-alla-pace","status":"publish","type":"post","link":"https:\/\/staging.premrawat.com\/it\/giornata-mondiale-di-educazione-alla-pace\/","title":{"rendered":"Giornata mondiale di Educazione alla Pace"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;2px|||||&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.22.1&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;20px&#8221; text_line_height=&#8221;1.4em&#8221; link_text_color=&#8221;#1565b7&#8243; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;30px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p><a href=\"https:\/\/lu.ma\/GPED2023\"><b><i>Registrati qui<\/i><\/b><\/a><b><i>\u00a0<\/i><\/b><b><i><\/i><\/b><\/p>\n<p><i>Come possiamo dare ai nostri bambini una voce e una scelta?<\/i><\/p>\n<p>\u00c8 questa la domanda che importanti educatori alla pace, leader della societ\u00e0 civile e funzionari delle Nazioni Unite affronteranno il 20 settembre alla terza conferenza annuale <a href=\"https:\/\/www.globalpeaceeducation.com\/our-next-event\">Online Conference for <i>Global Peace Education Day<\/i><\/a> per la Giornata mondiale dell&#8217;educazione alla pace (GPEN) &#8211; una conferenza che onorer\u00e0 il 75\u00b0 anniversario della Dichiarazione universale dei diritti umani. Il tema della conferenza \u00e8 &#8220;Diritti umani &#8211; dare responsabilit\u00e0 ai bambini&#8221;.<\/p>\n<p>A questa importante iniziativa parteciperanno pi\u00f9 di venti relatori e centinaia di colleghi attivisti per la pace, educatori, diplomatici, dignitari, studiosi, scienziati, artisti, atleti e dirigenti.<\/p>\n<p><a href=\"https:\/\/staging.premrawat.com\/it\/chi-e-prem-rawat\/\">Prem Rawat<\/a> terr\u00e0 una presentazione sul tema <i>\u201cDare responsabilit\u00e0 ai giovani con l\u2019Educazione alla Pace\u201d.<\/i><\/p>\n<p>Willow Baker, manager del <a href=\"https:\/\/tprf.org\/peace-education-program\/\">Programma di Educazione alla Pace<\/a> della TPRF, presenter\u00e0 un nuovo video &#8211; <i>Uno spazio per la pace &#8211; <\/i>che illustra l&#8217;impatto dell&#8217;educazione alla pace sugli studenti delle scuole superiori di Newburyport, in Massachusetts.<\/p>\n<p>Tra gli altri relatori della conferenza GPEN ci saranno:<\/p>\n<p><b>Presidente della conferenza: <\/b>Stefania Giannini, vicedirettore generale per l&#8217;Educazione dell&#8217;UNESCO.<\/p>\n<p><b>Presentatore: <\/b>Federico Mayor Zaragoza, Presidente della Fondazione per una Cultura di Pace e ex Direttore generale dell&#8217;UNESCO.<\/p>\n<p><b>Relatore<\/b>: Michael Nouri, attore cinematografico e teatrale; ambasciatore per Seeds of Peace<\/p>\n<p><b>Ambassador Anwarul K. Chowdhury<\/b>: Ex Sottosegretario Generale e Alto rappresentante delle Nazioni Unite; fondatore del Movimento Globale per la Cultura della Pace.<\/p>\n<p><b>Doudou Diene<\/b>: Giurista senegalese; ex Relatore Speciale, Nazioni Unite<\/p>\n<p><b>Ouided Bouchamaoui<\/b>: Premio Nobel per la Pace; Amministratore delegato del Gruppo H\u00e9di Bouchamaoui (HBG Holding); ex Presidente della Confederazione Tunisina dell&#8217;Industria, del Commercio e dell&#8217;Artigianato<\/p>\n<p><b>Diane Whitehead<\/b>: Amministratore delegato, Childhood Education International<\/p>\n<p><b>Dott. Marty Casey<\/b>: Fondatore, Istituto unGun, St. Louis, Missouri<\/p>\n<p><a href=\"https:\/\/lu.ma\/GPED2023\">La registrazione \u00e8 gratuita<\/a>. Una donazione \u00e8 gradita, ma non richiesta. Ai partecipanti sar\u00e0 inviato un link alla conferenza il giorno dell&#8217;evento. Sar\u00e0 disponibile la traduzione in spagnolo e francese.<\/p>\n<p><a href=\"https:\/\/www.globalpeaceeducation.com\/our-next-event\">Maggiori informazioni sulla conferenza<\/a><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.22.1&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;museo-sans|700|||||||&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;rgba(0,0,0,0.7)&#8221; custom_margin=&#8221;40px||||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h3>Related Articles<\/h3>\n<p><span style=\"color: #1565b7;\"><a href=\"https:\/\/staging.premrawat.com\/it\/category\/programma-di-educazione-alla-pace\/\" style=\"color: #1565b7;\">Programma di Educazione alla Pace<\/a><\/span> | <a href=\"https:\/\/staging.premrawat.com\/it\/category\/aiuti-umanitari\/\"><span style=\"color: #1565b7;\">Aiuti umanitari<\/span> <\/a>| <span style=\"color: #1565b7;\"><a href=\"https:\/\/staging.premrawat.com\/it\/category\/eventi\/\" style=\"color: #1565b7;\">Eventi<\/a><\/span>[\/et_pb_text][dgbc_blog_carousel type=&#8221;3&#8243; include_categories=&#8221;3701,3696&#8243; offset_number=&#8221;1&#8243; show_categories=&#8221;off&#8221; show_author=&#8221;off&#8221; show_date=&#8221;off&#8221; show_items_xlarge=&#8221;3&#8243; dot_nav=&#8221;on&#8221; inner_container_padding=&#8221;||||false|false&#8221; content_margin=&#8221;10px||||false|false&#8221; post_content_padding=&#8221;||0px||false|false&#8221; _builder_version=&#8221;4.22.1&#8243; _module_preset=&#8221;default&#8221; header_font_size=&#8221;21px&#8221; header_line_height=&#8221;1.2em&#8221; content_font_size=&#8221;16px&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/dgbc_blog_carousel][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Registrati qui\u00a0 Come possiamo dare ai nostri bambini una voce e una scelta? \u00c8 questa la domanda che importanti educatori alla pace, leader della societ\u00e0 civile e funzionari delle Nazioni Unite affronteranno il 20 settembre alla terza conferenza annuale Online Conference for Global Peace Education Day per la Giornata mondiale dell&#8217;educazione alla pace (GPEN) &#8211; [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":40775,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[4115,4005,3931],"tags":[4202,4203],"podcast-category":[],"class_list":["post-40902","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi-it","category-programma-di-educazione-alla-pace","category-umanitario","tag-peace-education-it","tag-peace-educators-it"],"acf":[],"_links":{"self":[{"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/posts\/40902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/comments?post=40902"}],"version-history":[{"count":9,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/posts\/40902\/revisions"}],"predecessor-version":[{"id":41053,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/posts\/40902\/revisions\/41053"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/media\/40775"}],"wp:attachment":[{"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/media?parent=40902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/categories?post=40902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/tags?post=40902"},{"taxonomy":"podcast-category","embeddable":true,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/podcast-category?post=40902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}