!function(e){var t={};function o(i){if(t[i])return t[i].exports;var r=t[i]={i:i,l:!1,exports:{}};return e[i].call(r.exports,r,r.exports,o),r.l=!0,r.exports}o.m=e,o.c=t,o.d=function(e,t,i){o.o(e,t)||Object.defineProperty(e,t,{enumerable:!0,get:i})},o.r=function(e){"undefined"!=typeof Symbol&&Symbol.toStringTag&&Object.defineProperty(e,Symbol.toStringTag,{value:"Module"}),Object.defineProperty(e,"__esModule",{value:!0})},o.t=function(e,t){if(1&t&&(e=o(e)),8&t)return e;if(4&t&&"object"==typeof e&&e&&e.__esModule)return e;var i=Object.create(null);if(o.r(i),Object.defineProperty(i,"default",{enumerable:!0,value:e}),2&t&&"string"!=typeof e)for(var r in e)o.d(i,r,function(t){return e[t]}.bind(null,r));return i},o.n=function(e){var t=e&&e.__esModule?function(){return e.default}:function(){return e};return o.d(t,"a",t),t},o.o=function(e,t){return Object.prototype.hasOwnProperty.call(e,t)},o.p="",o(o.s=8)}([function(e,t){e.exports=window.wp.data},function(e,t){e.exports=window.wp.element},function(e,t){e.exports=window.wp.components},function(e,t){e.exports=window.wp.i18n},function(e,t,o){"use strict";Object.defineProperty(t,"__esModule",{value:!0}),t.redirectOnSaveCompletion=void 0;var i=o(0),r=function(e){var t=(0,i.select)("core/editor").getCurrentPostAttribute("status"),o=(0,i.select)("core/editor").getEditedPostAttribute("status");"dp-rewrite-republish"===t&&"publish"===o&&(0,i.dispatch)("core/editor").editPost({status:t}),window.location.assign(e)};t.redirectOnSaveCompletion=function(e,t){var o=(0,i.select)("core/editor").isSavingPost(),n=(0,i.select)("core/editor").isAutosavingPost(),s=(0,i.select)("core/edit-post").hasMetaBoxes(),a=(0,i.select)("core/edit-post").isSavingMetaBoxes();return s&&!a&&t.wasSavingMetaboxes&&r(e),s||o||!t.wasSavingPost||t.wasAutoSavingPost||r(e),{isSavingPost:o,isSavingMetaBoxes:a,isAutosavingPost:n}}},,,,function(e,t,o){"use strict";var i=o(1),r=o(2),n=o(3),s=o(0),a=o(4);var u,l,c,p=function(){(0,s.dispatch)("core/editor").savePost();var e=!1,t=!1,o=!1;(0,s.subscribe)((function(){var i=(0,a.redirectOnSaveCompletion)(duplicatePostStrings.checkLink,{wasSavingPost:e,wasSavingMetaboxes:t,wasAutoSavingPost:o});e=i.isSavingPost,t=i.isSavingMetaBoxes,o=i.isAutosavingPost}))},d={Publish:(0,n.__)("Republish","duplicate-post"),"Publish:":(0,n.__)("Republish:","duplicate-post"),"Publish on:":(0,n.__)("Republish on:","duplicate-post"),"Are you ready to publish?":(0,n.__)("Are you ready to republish your post?","duplicate-post"),"Double-check your settings before publishing.":(0,i.createInterpolateElement)((0,n.__)("After republishing your changes will be merged into the original post and you'll be redirected there.<br /><br />Do you want to compare your changes with the original version before merging?<br /><br /><button>Save changes and compare</button>","duplicate-post"),{button:wp.element.createElement(r.Button,{isSecondary:!0,onClick:p}),br:wp.element.createElement("br",null)}),Schedule:(0,n.__)("Schedule republish","duplicate-post"),"Schedule…":(0,n.__)("Schedule republish…","duplicate-post"),"post action/button labelSchedule":(0,n.__)("Schedule republish","duplicate-post"),"Are you ready to schedule?":(0,n.__)("Are you ready to schedule the republishing of your post?","duplicate-post"),"Your work will be published at the specified date and time.":(0,i.createInterpolateElement)((0,n.__)("You're about to replace the original with this rewritten post at the specified date and time.<br /><br />Do you want to compare your changes with the original version before merging?<br /><br /><button>Save changes and compare</button>","duplicate-post"),{button:wp.element.createElement(r.Button,{isSecondary:!0,onClick:p}),br:wp.element.createElement("br",null)}),"is now scheduled. It will go live on":(0,n.__)(", the rewritten post, is now scheduled to replace the original post. It will be published on","duplicate-post")};for(var b in d)(0,n.setLocaleData)((c=[d[b],"duplicate-post"],(l=b)in(u={})?Object.defineProperty(u,l,{value:c,enumerable:!0,configurable:!0,writable:!0}):u[l]=c,u))}]);{"id":39103,"date":"2023-06-26T13:48:26","date_gmt":"2023-06-26T17:48:26","guid":{"rendered":"https:\/\/www.premrawat.com\/intervista-a-charan-anand-uno-di-noi\/"},"modified":"2023-07-20T09:36:42","modified_gmt":"2023-07-20T13:36:42","slug":"intervista-a-charan-anand-uno-di-noi","status":"publish","type":"post","link":"https:\/\/staging.premrawat.com\/it\/intervista-a-charan-anand-uno-di-noi\/","title":{"rendered":"Intervista a Charan Anand \u2013 Uno di noi"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;2px|||||&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;20px&#8221; text_line_height=&#8221;1.4em&#8221; link_text_color=&#8221;#1565b7&#8243; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;30px||0px|||&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p><b><i>La redattrice di <\/i><\/b><a href=\"https:\/\/staging.premrawat.com\/it\/\"><b><i>PremRawat.com<\/i><\/b><\/a>, <b><i>Marcia Newman<\/i><\/b>,<b><i> parla con Charan Anand<\/i><\/b><i>, da sempre sostenitore della pace interiore insegnata da Prem Rawat e dal padre e insegnante di Prem, Shri Maharaji. <\/i><i><\/i><i>Da oltre settant\u2019anni Charan Anand, ora novantaduenne, incontra in tutto il mondo migliaia di persone interessate ad approfondire l\u2019esperienza della <\/i><a href=\"https:\/\/staging.premrawat.com\/it\/conoscenza-del-se\/\"><i>Conoscenza del S\u00e9<\/i><\/a> <i><\/i><i>che Prem Rawat offre gratuitamente. L\u2019intervista che segue \u00e8 una rara occasione per i lettori di scoprire le umili origini di Charan Anand, le sue straordinarie esperienze e la sua grande considerazione del valore della pratica della Conoscenza del S\u00e9.<\/i><\/p>\n<p><b>PremRawat.com<\/b>: Grazie di essere con noi oggi, Charan Anand. Complimenti per i tuoi 92 anni festeggiati da poco!<\/p>\n<p><b>Charan Anand: <\/b>Vi ringrazio molto per avermi offerto l\u2019opportunit\u00e0 di esprimere i miei sentimenti. Anche se il mio corpo ha 92 anni, dentro mi sento senza et\u00e0.<\/p>\n<p><b>PremRawat.com<\/b>: Cominciamo da oggi. Come ti trovi ad Aventura, in Florida, e cosa fai di bello di questi tempi?<\/p>\n<p><b>Charan Anand: <\/b>Sono molto felice (<i>ride<\/i>) e mi diverto tanto. Mi godo la pratica della Conoscenza e ascolto il messaggio di Prem. Mi piace stare all\u2019aperto e fare un poco di ginnastica tutti i giorni. Quando posso, mi piace ancora giocare a golf.<\/p>\n<p><b>PremRawat.com: <\/b>\u00c8 bello sapere che stai bene. Veniamo al sodo: oggi come spiegheresti la Conoscenza del S\u00e9 a una persona interessata?<\/p>\n<p><b>Charan Anand: <\/b>\u00c8 molto semplice. Prem Rawat insegna una pratica quotidiana chiamata Conoscenza o Conoscenza del S\u00e9. \u00c8 un metodo naturale per rivolgere dentro s\u00e9 stessi la propria attenzione e sentire la pace che gi\u00e0 vi si trova. Per me \u00e8 un\u2019esperienza semplice e piacevole.<\/p>\n<p><b>PremRawat.com: <\/b>Come descriveresti il tuo rapporto con Prem Rawat?<\/p>\n<p><b>Charan Anand: <\/b>Gli voglio bene e lo rispetto come maestro, e lo porto nel cuore come l\u2019amico pi\u00f9 caro che ho.<\/p>\n<p><b>PremRawat.com: <\/b>Tu sei comparso nella serie di Nic Askew <a href=\"https:\/\/soulbiographies.com\/library\/the-riddle-of-here\/\">Soul Biographies<\/a>. In quel bellissimo video hai accennato di essere cresciuto in un piccolo villaggio indiano in una famiglia molto unita. Raccontaci di te da giovane.<\/p>\n<p><b>Charan Anand: <\/b>Sono nato nel villaggio di Sudar Pura, vicino a Kotpuli nel Rajastan, in India. Era circondato da bellissime campagne site fra due alte colline. Mio padre era un uomo molto affettuoso, buono e generoso. Quando avevo otto anni ci fu una terribile siccit\u00e0 nella nostra regione e i contadini del villaggio presero del denaro a prestito per restare a galla. Mio padre, che aveva una falegnameria, diede in garanzia il valore della sua azienda per sostenere quei prestiti. Dato che la siccit\u00e0 continuava e i creditori facevano pressione, mio padre decise di andare a lavorare in altri villaggi con i suoi operai, per guadagnare di pi\u00f9 e pagare i prestiti. Io venni ritirato dalla scuola per aiutare a preparare i pasti per chi partiva e anche per aiutare in falegnameria. Per questo motivo ho frequentato solo due anni di scuola. Comunque imparai a cucinare veramente bene, un\u2019abilit\u00e0 che mi \u00e8 stata molto utile in tutti questi anni. Crescendo, volli sviluppare le mie capacit\u00e0 nell\u2019arte della falegnameria. Cos\u00ec contattai un parente di Delhi che era molto esperto in quel settore, e lui mi invit\u00f2 ad andare a stare da lui a Delhi. Avevo circa 17 anni.<\/p>\n<p><b>PremRawat.com: <\/b>Fu allora che sentisti parlare per la prima volta del messaggio di pace interiore insegnato da Shri Maharaji, il padre di Prem Rawat?<\/p>\n<p><b>Charan Anand: <\/b>S\u00ec, andai a stare a Delhi dal mio parente Prahlad, che aveva la Conoscenza. Un giorno egli mi invit\u00f2 ad andare ad ascoltare una persona che si chiamava Om Prakash Ji, che parlava a nome del suo maestro Shri Maharaji. Om Prakash era uno studente molto vicino a Shri Maharaji e gli era stato chiesto di diffondere il messaggio del suo maestro. Egli parlava con grande sincerit\u00e0 e i suoi discorsi mi furono di grande ispirazione. Egli sottolineava che bisogna conoscere un modo pratico per mettersi in contatto con la pace che si trova dentro di noi. Questo accadeva nel 1948. Om Prakash aveva il permesso di Shri Maharaji di mostrare le tecniche della Conoscenza del S\u00e9. Ma quando glielo chiesi, lui disse: \u201cNo, \u00e8 meglio che aspetti ancora. Se \u00e8 la Conoscenza che vuoi davvero, la avrai.\u201d<\/p>\n<p>Mi incoraggi\u00f2 ad ascoltare ancora e a incontrare Shri Maharaji in persona. Om Prakash Ji disse: \u201cTi ho parlato della mia esperienza con Shri Maharaji e il suo dono della Conoscenza. Ma ora voglio che tu lo incontri ed entri in rapporto diretto con lui.\u201d<\/p>\n<p><b>PremRawat.com: <\/b>Quando hai incontrato Shri Maharaji? Cosa ti ricordi di lui in quell\u2019occasione?<\/p>\n<p><b>Charan Anand: <\/b>Un giorno finalmente vidi una foto di Shri Maharaji. Quella notte il desiderio di vederlo divenne molto intenso, infatti sognai che Shri Maharaji veniva a Delhi su un bellissimo carro mentre il cielo splendeva di luce. Il mattino seguente qualcuno mi inform\u00f2 che Shri Maharaji era arrivato a Delhi e io ne fui felicissimo. Fui invitato ad andare ad ascoltarlo. Quando lo vidi per la prima volta fui impressionato dal suo aspetto radioso, bellissimo e regale. Il mio sogno si era avverato.<\/p>\n<p>Il suo messaggio di pace era semplice, diretto e profondamente toccante. All\u2019evento, a quelli che si fecero avanti e gli chiesero sinceramente la Conoscenza, lui disse: \u201cVa bene.\u201d Quella volta non ebbi il coraggio di alzarmi di fronte ad altre persone per esprimere il mio desiderio. Pensai che forse Om Prakash Ji l\u2019avrebbe chiesta per me o almeno mi avrebbe presentato a Shri Maharaji (<i>ride).<\/i><\/p>\n<p><b>PremRawat.com: <\/b>Chiaramente, alla fine sei riuscito a trovare il coraggio di chiedere a Shri Maharaji di ricevere le tecniche della <a href=\"https:\/\/staging.premrawat.com\/it\/conoscenza-del-se\/\">Conoscenza del S\u00e9<\/a>.<\/p>\n<p><b>Charan Anand: <\/b>L\u2019evento di Shri Maharaji continu\u00f2 per tre giorni. Di notte non riuscivo a dormire a causa di una sensazione molto forte, come un desiderio profondo. Nei sogni, chiedevo di ricevere il dono della Conoscenza. Il mattino dopo che l\u2019evento di Shri Maharaji si era concluso, me ne stavo tornando al lavoro quando incontrai Prahlad che mi disse che Om Prakash Ji voleva portarmi in visita da Shri Maharaji alla residenza di Delhi. Quando arrivammo, Shri Maharaji chiese a Om Prakash chi io fossi. Om Prakash inform\u00f2 Shri Maharaji che avevo ascoltato e che ero un aspirante (una persona che aspira a ricevere la Conoscenza). Shri Maharaji mi guard\u00f2 e chiese: \u201cQuanti anni hai?\u201d Risposi: \u201c18 anni.\u201d<\/p>\n<p>Shri Maharaji chiese: \u201cPerch\u00e9 ti serve la Conoscenza in questo momento della tua vita? Sei giovane, vai a divertirti.\u201d<\/p>\n<p>Dal profondo di me, mi sentii rispondere a Shri Maharaji: \u201cS\u00ec, la mia vita va benissimo, ma senza la Conoscenza sento che sarebbe vuota. Sento che nella vita c\u2019\u00e8 di pi\u00f9. Perci\u00f2 chiedo umilmente di poter ricevere la tua Conoscenza.\u201d<\/p>\n<p>Mi sentivo cos\u00ec a mio agio in sua presenza che risposi alla sua domanda in tutta sincerit\u00e0.<\/p>\n<p>Shri Maharaji allora si chin\u00f2 benevolmente verso di me e disse: \u201cVa bene.\u201d Poi chiese a Om Prakash Ji di mostrarmi le tecniche e quel giorno ricevetti la benedizione di questo bellissimo dono della Conoscenza.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/cdn.premrawat.com\/2023\/06\/Charan-Anand-Europe-1974.jpg&#8221; alt=&#8221;CharanAnand_Europe Younger \u2013 Europa 1974&#8243; title_text=&#8221;Charan-Anand-Europe-1974&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;53px||15px||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;20px&#8221; link_text_color=&#8221;#1565b7&#8243; custom_margin=&#8221;||18px||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p style=\"text-align: right;\"><span style=\"font-size: small;\">Charan Anand \u2013 Europa 1974<\/span><\/p>\n<p><b>PremRawat.com: <\/b>Ho sentito dire che oltre 50 persone nel tuo villaggio natio, molte delle quali tue parenti, hanno finito per ricevere la Conoscenza. \u00c8 vero?<\/p>\n<p><b>Charan Anand: <\/b>S\u00ec. Mio fratello maggiore inizi\u00f2 a interessarsi e anche lui ricevette la Conoscenza. Disse a tutti: \u201c\u00c8 un dono bellissimo, chiedetela anche voi.\u201d Io avevo anche un gran desiderio di invitare Shri Maharaji nel mio villaggio. Ci venne due volte. Una volta fu durante la stagione delle piogge e il suo autobus rest\u00f2 bloccato nel fango. Shri Maharaji scese dal bus e inizi\u00f2 a camminare a piedi nudi verso il villaggio. Uno degli organizzatori si arrabbi\u00f2 e cominci\u00f2 a criticarmi per aver organizzato un evento in un posto cos\u00ec difficile da raggiungere. Ricordo come rispose Shri Maharaji: si volt\u00f2 verso quello che criticava e disse: \u201cNon dire cos\u00ec. Se mi si invita con il cuore, andr\u00f2 in qualunque posto. Andr\u00f2 da chiunque mi inviti con il cuore.\u201d<\/p>\n<p>Anche se mi sentivo in imbarazzo per la situazione, Shri Maharaji mi aveva confortato.<\/p>\n<p><b>PremRawat.com: <\/b>Che maestro serio e comprensivo! Fu poco dopo quell\u2019evento al tuo paese che Shri Maharaji ti chiese di aiutarlo a diffondere il suo messaggio?<\/p>\n<p><b>Charan Anand: <\/b>Un giorno ebbi occasione di parlare in privato con Shri Maharaji.<\/p>\n<p>Mi domand\u00f2: \u201cDove abiti?\u201d \u201cA Delhi.\u201d \u201cCosa fai?\u201d \u201cFaccio il falegname.\u201d \u201cChe ne pensi della Conoscenza?\u201d Risposi: \u201c\u00c8 la cosa pi\u00f9 bella della mia vita.\u201d<\/p>\n<p>\u201cPensi che questa Conoscenza dovrebbe essere messa a disposizione degli altri esseri umani?\u201d<\/p>\n<p>\u201cAssolutamente s\u00ec,\u201d risposi.<\/p>\n<p>\u201cE chi lo far\u00e0?\u201d<\/p>\n<p>\u201cShri Maharaji, tu insieme ai tuoi studenti.\u201d \u201cE tu chi sei? Non sei uno dei miei studenti?\u201d \u201cS\u00ec.\u201d<\/p>\n<p>\u201cLa falegnameria per te \u00e8 pi\u00f9 importante che aiutarmi nel mio lavoro?\u201d<\/p>\n<p>\u201cAssolutamente no.\u201d<\/p>\n<p>Allora lui disse: \u201cDunque cosa aspetti?\u201d<\/p>\n<p>Dissi: \u201cNiente.\u201d Nonostante ci\u00f2, dovetti dedicare un po\u2019 di tempo alle mie responsabilit\u00e0 familiari: purtroppo mio padre era morto e mia madre non ci vedeva pi\u00f9 bene. Mio fratello minore e sua moglie riuscirono a farsi carico di nostra madre.<\/p>\n<p>Quando cominciai ad aiutare Shri Maharaji, lui disse ai membri della sua famiglia: \u201cQuesta persona mi aiuter\u00e0 molto nel diffondere il mio messaggio.\u201d<\/p>\n<p>Era settembre 1957, tre mesi prima che nascesse Prem.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/cdn.premrawat.com\/2023\/06\/Charan-Anand-Leicester-UK-1971.jpg&#8221; alt=&#8221;CharanAnand_Europe Younger \u2013 Europa 1974&#8243; title_text=&#8221;Charan Anand &#8211; Leicester UK 1971&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||15px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;20px&#8221; link_text_color=&#8221;#1565b7&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p style=\"text-align: right;\"><span style=\"font-size: small;\">aran Anand parla a Leicester, Regno Unito \u2013 1971<br \/><\/span><\/p>\n<p><b>PremRawat.com:<\/b>\u00a0Allora tu viaggiasti per tutta l\u2019India con un altro mahatma (istruttore) di nome Ramanand, alloggiando presso altre persone. Come fu questo per te?<\/p>\n<p><b>Charan Anand:<\/b>\u00a0S\u00ec, andammo in varie citt\u00e0, iniziando da Jaipur. C\u2019erano luoghi in cui potevi alloggiare gratuitamente. Io andavo ad annunciare l\u2019evento e la gente veniva ad ascoltare. Alcuni venivano ispirati e ci invitavano a casa loro per cena. Pian piano \u00e8 cos\u00ec che tutto ebbe inizio. Infine arrivammo a Mumbai. Non c\u2019era neanche una persona che avesse la Conoscenza, a quei tempi. Ora, con gli eventi globali di Prem, accade cos\u00ec tanto in India e dappertutto!\u00a0<\/p>\n<p>In quei primi tempi salii per la prima volta su un aereo, che port\u00f2 Shri Maharaji e me da Mumbai a Delhi. Egli mi chiese di mangiare la colazione che stavano servendo sull\u2019aereo; dato che lui non la prendeva e io non ero mai stato su un aereo prima di allora, esitai. Shri Maharaji insistette che dovevo mangiare. Dopo che fummo arrivati a Delhi e io sedevo con lui in camera sua, mi disse: \u201cSai perch\u00e9 ti ho chiesto di mangiare in aereo?\u201d<\/p>\n<p>Risposi: \u201cNo\u201d<\/p>\n<p>Allora Shri Maharaji spieg\u00f2: \u201cIn futuro, tu andrai in Occidente a presentare la Conoscenza alle persone; ecco perch\u00e9 volevo che ti abituassi ai viaggi aerei.\u201d<\/p>\n<p>Mi sentii stupito ed euforico nel sentirgli dire questo. Gli chiesi umilmente: \u201cShri Maharaji, come far\u00f2 ad andare nei paesi occidentali, se non so l\u2019inglese?\u201d<\/p>\n<p>Rispose: \u201cSappi che quando ci sono fiducia e impegno, qualunque cosa \u00e8 possibile.\u201d<\/p>\n<p>Quell\u2019episodio mi ispir\u00f2 a imparare l\u2019inglese. Pi\u00f9 tardi, quando Prem Rawat mi mand\u00f2 in Inghilterra nel 1969, seppi che la profezia di Shri Maharaji si era avverata nella mia vita: in effetti, ho continuato a viaggiare per tutto il mondo portando il suo messaggio da quei tempi fino alla pandemia del 2020.<\/p>\n<p><b>PremRawat.com: <\/b>Incredibile! Passiamo a luglio 1966, Charan Anand: stavi collaborando a un evento ad Alwar, nel Rajastan, con Shri Maharaji. Quella fu l\u2019ultima volta che lo vedesti. Shri Maharaji manc\u00f2 dopo pochi giorni, all\u2019et\u00e0 di 66 anni. Cosa ti ricordi di quei momenti?<\/p>\n<p><b>Charan Anand: <\/b>S\u00ec, ero gi\u00e0 ad Alwar, ad aiutare a preparare l\u2019evento. Avevamo persino invitato il governatore di Alwar, che contava di intervenire. Shri Maharaji arriv\u00f2 ad Alwar e pi\u00f9 tardi quella sera parl\u00f2 a Ramanand e me e disse che non si sentiva bene. Shri Maharaji ci chiese di portare il suo messaggio, amore e benedizioni a tutto il pubblico. Bihari Singh chiese a Shri Maharaji: \u201cVuoi tornare a casa tua a Dehradun?\u201d Shri Maharaji rispose: \u201cNo, voglio andare a Delhi.\u201d<\/p>\n<p>Bihari lo condusse in auto a Shakti Nagar, la sua casa a Delhi. Shri Maharaji voleva stare da solo senza parlare con nessuno. Continu\u00f2 a praticare la Conoscenza tutto il giorno, senza smettere per mangiare o bere. \u00c8 in questo modo che scelse di lasciare il suo corpo, in pace.<\/p>\n<p>Per me, questo \u00e8 veramente notevole. Shri Maharaji amava la sua famiglia e amava i suoi studenti. C\u2019erano sempre persone che venivano a trovarlo. Ma quando per lui arriv\u00f2 il momento di lasciare il suo corpo, non volle vedere nessuno. Questo rimane di grande ispirazione per me. Evidenzia quanto fu raccontato nella Bhagavad Gita quando Arjuna chiede a Krishna: \u201cQual \u00e8 la natura di una persona che \u00e8 veramente in comunicazione con l\u2019esperienza interiore?\u201d<\/p>\n<p>Krishna risponde: \u201cQuella persona \u00e8 come una tartaruga. Pu\u00f2 far uscire le zampe e muoversi, ma quando il suo guscio viene colpito, pu\u00f2 ritrarre i suoi arti all\u2019interno. La persona che \u00e8 connessa con l\u2019esperienza interiore pu\u00f2 ritrarre la sua attenzione dal mondo e rivolgerla dentro di s\u00e9.\u201d<\/p>\n<p>Shri Maharaji sapeva cosa gli era pi\u00f9 prezioso: quella gioia interiore.<\/p>\n<p><b>PremRawat.com:<\/b>\u00a0Grazie di averci raccontato le tue esperienze con Shri Maharaji. Cosa trovi particolarmente convincente nel modo in cui Prem Rawat comunica il suo messaggio di pace?<\/p>\n<p><b>Charan Anand:<\/b>\u00a0La prima volta che vidi Prem lui aveva tre mesi. Quando lo tenni in braccio per la prima volta, rimasi molto impressionato guardando il suo viso sereno e radioso. Pochi giorni dopo, mentre lo teneva in braccio, Shri Maharaji disse: \u201cQuello che porter\u00e0 il mio messaggio in tutto il mondo sta fra le mie braccia.\u201d Quando Prem aveva quattro anni, lo vedevo a Dehradun seduto fermo fuori nella veranda, assorto in s\u00e9 stesso. Lo faceva ogni mattina. Ne ero sbalordito e ispirato. Poi veniva a bussare alla porta della mia stanza nella casa degli ospiti e mi diceva di svegliarmi e di praticare la Conoscenza. Io gli sorridevo e gli chiedevo: \u201cPer favore pratica con me.\u201d Allora lui sedeva con me mentre praticavo.<\/p>\n<p>In quel periodo, un signore anziano venne a trovare Shri Maharaji e mi chiese di parlare con lui. Iniziammo la nostra conversazione durante la quale Sant Ji (Prem) entr\u00f2 e mi si sedette in braccio a osservare quel che stava accadendo. Il signore anziano, che era molto colto, inizi\u00f2 a discutere con me citando vari riferimenti ai libri che aveva letto. A un certo punto Sant Ji lo interruppe e chiese a quel signore: \u201cQuanti anni hai?\u201d\u00a0<\/p>\n<p>La risposta fu: \u201c75\u201d<\/p>\n<p>\u201cHai trovato la pace che stai cercando?\u201d<\/p>\n<p>\u201cNo, non ancora.\u201d<\/p>\n<p>Allora Sant Ji lo ammon\u00ec: \u201cNon discutere con Charan Anand. Lui parla della sua esperienza della Conoscenza e non delle sue letture. Non perdere tempo, sei gi\u00e0 abbastanza vecchio. Chiedi a Shri Maharaji il dono della Conoscenza che ti aiuter\u00e0 a sperimentare personalmente la pace interiore.\u201d<\/p>\n<p>Detto questo, Sant Ji mi chiese di allontanarmi con lui un momento. Quando tornai, trovai il vecchio signore che rifletteva in silenzio.<\/p>\n<p>Mi chiese: \u201cChi era quel ragazzino?\u201d<\/p>\n<p>Io dissi: \u201c\u00c8 il figlio minore di Shri Maharaji.\u201d<\/p>\n<p>Il vecchio disse: \u201cHo incontrato tante persone nella mia vita, ma nessuno mi ha lasciato senza parole come ha fatto lui. La sua domanda \u00e8 stata cos\u00ec diretta, e ho dovuto ammettere di non avere trovato la pace con le mie letture.\u201d<\/p>\n<p>Dopo poco tempo, chiese e ricevette da Shri Maharaji il dono della Conoscenza. Fu davvero ispirante vedere quanto, persino a un\u2019et\u00e0 cos\u00ec giovane, Prem fosse dotato nell\u2019aiutare gli altri a entrare in contatto con il loro vero s\u00e9.<\/p>\n<p>Shri Maharaji parlava sempre di Sant Ji con tale amore, ammirazione e fiducia. Lui sapeva davvero chi fosse Prem.<\/p>\n<p>Perci\u00f2 lo iscrisse a una scuola inglese perch\u00e9 acquisisse una buona padronanza della lingua. Di tanto in tanto dichiarava: \u201cQuello che diffonder\u00e0 la Conoscenza in tutto il mondo \u00e8 qui tra noi.\u201d<\/p>\n<p>Un giorno un pandit chiese a Shri Maharaji: \u201cPerch\u00e9 non mandi Sant Ji a una scuola di sanscrito invece che a una scuola di inglese?\u201d<\/p>\n<p>Shri Maharaji chiese: \u201cPerch\u00e9 ha bisogno di imparare il sanscrito?\u201d<\/p>\n<p>Il pandit disse: \u201cCos\u00ec sar\u00e0 in grado di leggere le nostre antiche scritture.\u201d<\/p>\n<p>Shri Maharaji rispose: \u201cNon ha bisogno di leggere le scritture. Quando parler\u00e0, saranno scritti dei nuovi testi.\u201d<\/p>\n<p>Un\u2019altra volta, mentre ero con lui a Mumbai, Shri Maharaji mi chiese di scrivere una lettera a sua moglie, Mata Ji, per esprimere la sua preoccupazione di non poter partecipare al festival Guru Puja quell\u2019anno. Voleva che Sant ji (Prem) sedesse sulla sua sedia e che tutti i suoi studenti celebrassero il festival con lui.<\/p>\n<p>Pi\u00f9 tardi, quando aveva solo sette anni, Prem organizz\u00f2 un evento a Dehradun per Shri Maharaji, che in quel momento era in viaggio nel Punjab. Prem mand\u00f2 un invito a Shri Maharaji tramite un messaggero.<\/p>\n<p>Quando il messaggio venne recapitato, Shri Maharaji disse: \u201cNon c\u2019\u00e8 bisogno che io ci vada, perch\u00e9 c\u2019\u00e8 Sant Ji e si occuper\u00e0 lui di tutto.\u201d\u00a0<\/p>\n<p>Il messaggero rispose: \u201cSant Ji mi ha chiesto di portarti personalmente la sua richiesta.\u201d<\/p>\n<p>Shri Maharaji riflett\u00e8 un attimo e si sent\u00ec cos\u00ec commosso che disse: \u201cDevo andarci. Non voglio che Sant Ji si offenda, perch\u00e9 gli voglio tanto bene!\u201d Cos\u00ec disdisse i suoi impegni e part\u00ec per Dehradun nel bel mezzo della notte.<\/p>\n<p>Shri Maharaji rest\u00f2 molto colpito dal modo in cui Prem aveva organizzato l\u2019evento. Era tale la cura e l\u2019attenzione a ogni particolare che per gli eventi seguenti gli organizzatori in India cercarono di seguire il suo esempio. Prem aveva invitato i suoi insegnanti di scuola e molte persone di riguardo della citt\u00e0. L\u2019evento si sarebbe tenuto in un bellissimo parco una sera d\u2019estate. La luna era piena e l\u2019ambiente molto accattivante. Durante il suo discorso, Shri Maharaji chiam\u00f2 Sant Ji sul palco a parlare. Ricordo ancora l\u2019essenza del messaggio di Prem, rivolto sia in inglese che in hindi quella notte al popolo indiano.<\/p>\n<p>Il giovane Prem disse: \u201cPer quanto tempo ancora dipenderete dagli aiuti stranieri? Avete abbondanza di risorse per sviluppare il vostro paese. Tutto ci\u00f2 che dovete fare \u00e8 insegnare alla vostra gente a lavorare insieme. Altre nazioni hanno sviluppato i loro paesi, potete farcela anche voi. Ma non dimenticatevi della Conoscenza e della nostra antica saggezza. Lo sviluppo materiale da solo non pu\u00f2 portare vera soddisfazione e felicit\u00e0 nella vita umana. Si deve combinare la Conoscenza del s\u00e9 interiore con la tecnologia moderna.\u201d<\/p>\n<p>&nbsp;<\/p>\n<p>Mentre Prem parlava, guardavo sia Shri Maharaji che suo figlio, e vidi che Shri Maharaji era ammirato e deliziato. Fu di grande ispirazione per me guardare Sant Ji, a sette anni, che parlava sia in inglese che in hindi con grande sicurezza, chiarezza e facilit\u00e0 di fronte a Shri Maharaji e al pubblico. Quando Prem ebbe finito di parlare, Shri Maharaji prese una ghirlanda di fiori dal proprio collo e la mise a Prem, e parl\u00f2 di lui con orgoglio.<\/p>\n<p>Shri Maharaji disse: \u201cIl suo corpo \u00e8 piccolo, ma la sua anima \u00e8 grande. Senza dubbio lui metter\u00e0 questa Conoscenza a disposizione della gente del mondo. Lo ammiro non perch\u00e9 \u00e8 mio figlio, ma a causa della sua grande saggezza e abilit\u00e0.\u201d<\/p>\n<blockquote>\n<p>La vita \u00e8 molto preziosa, la vita \u00e8 sublime.<\/p>\n<p>Apprezziamo questo dono, finch\u00e9 siamo in tempo.<\/p>\n<\/blockquote>\n<p>Charan Anand<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;20px&#8221; link_text_color=&#8221;#1565b7&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p><b>Charan Anand:<\/b>\u00a0Prem aveva solo otto anni quando suo padre e suo maestro venne a mancare. Ci fu molta afflizione e confusione fra la famiglia e tutti coloro che lo circondavano. A quella tenera et\u00e0, naturalmente, anche Prem soffr\u00ec profondamente. Eppure, in una notte serena durante quel periodo, mi disse: \u201cSento la presenza di Shri Maharaji intorno a noi, per vedere se siamo persi nel nostro dolore o se ci ricordiamo quanto gli stesse a cuore la diffusione della Conoscenza.\u201d Restai sbalordito che un ragazzo cos\u00ec giovane avesse la forza interiore di sollevarsi dall\u2019intensa tristezza del momento e di restare in contatto con qualcosa che era tanto importante per suo padre. Il giorno seguente, il 31 luglio 1966, davanti ai miei occhi, parl\u00f2 a migliaia di persone in lutto, dicendo: \u201cNon piangete, non dovete piangere. Ci\u00f2 che amavate di Shri Maharaji sar\u00e0 sempre con voi. Nessuno ve lo potr\u00e0 mai togliere.\u201d<\/p>\n<p>Mentre continuava a parlare, Prem trasformava le lacrime in gioia, la confusione in chiarezza, la disperazione in speranza. Non scorder\u00f2 mai quei momenti cos\u00ec intensi. Fu un vero punto di svolta per tutti noi presenti. Prem tocc\u00f2 profondamente il nostro cuore e ci aiut\u00f2 a riconoscerlo come nostro maestro vivente. Prem non mi fece mai provare il senso di una transizione improvvisa, perch\u00e9 potevo sentire lo stesso amore e la stessa presenza.\u00a0<\/p>\n<p>Mesi dopo, nel novembre 1966, fu organizzato per Prem un grande evento a Delhi. In origine era stato pianificato per Shri Maharaji. Ad accogliere Prem Rawat venne il sindaco di Delhi. Questo ebbe luogo poco prima del suo nono compleanno. Il sindaco espresse il suo stupore per l\u2019abilit\u00e0 oratoria di Prem e si meravigli\u00f2: \u201cSe riesce a toccare cos\u00ec profondamente il cuore delle persone a un\u2019et\u00e0 cos\u00ec tenera, cosa riuscir\u00e0 a fare quando sar\u00e0 grande?\u201d<\/p>\n<p>Da allora in poi, durante le vacanze scolastiche Prem parl\u00f2 a migliaia di persone in diverse parti dell\u2019India. In pochi anni port\u00f2 il suo messaggio al resto del mondo. Spesso avevo visto gli occhi di Shri Maharaji riempirsi di lacrime mentre esprimeva il suo profondo desiderio che il dono della Conoscenza venisse reso disponibile in tutto il mondo.<\/p>\n<p>A mio sentire, quando un maestro esprime il sincero desiderio del suo cuore che accada qualcosa, presto o tardi accadr\u00e0. \u00c8 come se quei desideri venissero assorbiti nell\u2019atmosfera finch\u00e9 non arriva la persona giusta che se ne fa carico e li realizza. Quando quella persona inizia a farlo, tutte le risorse naturali le vengono in aiuto. Vedo che questo accade ora con l\u2019impegno di Prem Rawat e di quanti sostengono il suo messaggio di pace in tutto il mondo.<\/p>\n<blockquote>\n<p>A mio sentire, quando un maestro esprime il sincero desiderio del suo cuore che accada qualcosa, presto o tardi accadr\u00e0.<\/p>\n<\/blockquote>\n<p style=\"text-align: right;\">Charan Anand<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;20px&#8221; link_text_color=&#8221;#1565b7&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p><b>PremRawat.com:<\/b>\u00a0Incredibile. Grazie. Nel 1969 Prem ti chiese di portare il suo messaggio in Occidente, prima in Inghilterra e poi negli Stati Uniti. Dev\u2019essere stato un bello shock culturale, per te!<\/p>\n<p><b>Charan Anand:<\/b>\u00a0S\u00ec. Avevo gi\u00e0 conosciuto gruppi di giovani occidentali che erano venuti in India a cercare qualcosa di pi\u00f9 nella vita. All\u2019epoca, il loro stile di vita era strano per me. Sembrava che gli andasse bene dormire nei parchi, fumare la marijuana e vivere da hippy. Molti mi raccontavano la loro storia. Venni a sapere che erano stati cos\u00ec fortunati da poter studiare, crescere in un ambiente famigliare stabile e ricevere davvero tanto. Eppure dicevano di non essere del tutto felici. Questi giovani occidentali venivano in India per conoscere meglio l\u2019antica saggezza indiana. Alcuni di loro, con cui sono ancora in contatto, ora sono anziani e ancora coinvolti attivamente nel sostenere il bellissimo messaggio di pace di Prem. Quando Prem decise di mandarmi in Inghilterra, disse: \u201cVediamo quanto ne sai di inglese.\u201d<\/p>\n<p>Disse alcune parole in inglese e mi chiese di tradurle in hindi. Lo feci correttamente.<\/p>\n<p>Lui sorrise e mi disse: \u201cPerfetto. Ne sai abbastanza. Le persone percepiranno il significato di quello che dici, piuttosto che perdersi nelle parole.\u201d<\/p>\n<p>Il suo consiglio su come comportarmi una volta arrivato in Occidente fu di non criticare n\u00e9 di sostenere ci\u00f2 che le persone facevano nella loro vita privata. \u201cSe li critichi, non torneranno pi\u00f9. Se li sostieni, le autorit\u00e0 potrebbero arrestarti ed espellerti dall\u2019Inghilterra. Quindi non ci cascare. Porta semplicemente il mio messaggio. A chiunque sia interessato mostra le tecniche della Conoscenza del S\u00e9 e ispirali a praticare. Solo questo porter\u00e0 loro vera gioia e trasformazione.\u201d<\/p>\n<p>\u00a0Prem all\u2019epoca aveva 11 anni.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/cdn.premrawat.com\/2023\/06\/Prem_CharanAnandBihari_Toronto.jpg&#8221; title_text=&#8221;Prem_CharanAnand+Bihari_Toronto&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;20px&#8221; link_text_color=&#8221;#1565b7&#8243; custom_margin=&#8221;||50px|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p>Prem Rawat (a sinistra) con Bihari Singh e Charan Anand (a destra) a Toronto, Canada \u2013 1971<\/p>\n<p><b>PremRawat.com:\u00a0<\/b>In che modo, se lo \u00e8, la mentalit\u00e0 delle persone in Occidente era diversa nel 1971 rispetto a oggi? Che cosa, se lo \u00e8, \u00e8 cambiato secondo te?\u00a0\u00a0<\/p>\n<p><b>Charan Anand:\u00a0<\/b>Quanti cambiamenti avvengono nel mondo! Eppure, qualunque anno sia, molte delle persone che ascoltano Prem Rawat lo trovano di grande ispirazione. \u00c8 un messaggio senza tempo che invita a scoprire la propria sete di felicit\u00e0. Nessuno \u00e8 qui a persuadere nessuno. Con tutta la tecnologia e i cambiamenti del mondo, non c\u2019\u00e8 nulla che possa sostituire la conoscenza del s\u00e9. S\u00ec, \u00e8 importante progredire nella scienza, nella tecnologia e ricevere un\u2019istruzione completa. Per\u00f2 abbiamo anche bisogno di ricevere gli antichi insegnamenti che ci aiutano a vivere in pace, dignit\u00e0, prosperit\u00e0. Indipendentemente dalla sua et\u00e0, Prem esprime con sicurezza ci\u00f2 che ha nel cuore. Quando aveva 13 anni venne a Los Angeles e qualcuno gli chiese: \u201cDicci cosa succede dopo la morte.\u201d\u00a0<\/p>\n<p>Lui sorrise e disse: \u201cNon lo so, sono ancora vivo. Non preoccuparti, ci arriverai e poi non potrai dire a nessuno cosa succede. Non sono qui in America per parlare di questo tipo di cose. So solo che la vita \u00e8 preziosa. Vivi felicemente e consapevolmente.\u201d<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/cdn.premrawat.com\/2023\/06\/Prem_CharanAnand_Boulder-1.jpg&#8221; title_text=&#8221;Prem_CharanAnand_Boulder-1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;20px&#8221; link_text_color=&#8221;#1565b7&#8243; custom_margin=&#8221;||50px|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p>Charan Anand con Prem Rawat a Boulder, Colorado \u2013 1971<\/p>\n<p>Durante quel tour in varie citt\u00e0 dell\u2019America la gente continuava a fare tante domande. Alla fine lui disse: \u201cPerch\u00e9 mi fate tutte queste domande? Ho solo 13 anni. Non ho le risposte a queste domande, ho chiarezza perch\u00e9 il mio maestro mi ha messo in contatto col mio cuore per mezzo del dono della Conoscenza. Perch\u00e9 non mi chiedete quella e trovate da soli le vostre risposte?\u201d Penso che Kabir (santo e poeta indiano del 15\u00b0 secolo) sarebbe d\u2019accordo: \u201cTu parli di quello che hai letto e io parlo di quello che vivo personalmente.\u201d<\/p>\n<p><b>PremRawat.com:<\/b>Mi pare di capire che tu abbia letto la gran parte delle scritture di tutto il mondo. Cosa diresti che hanno in comune?<\/p>\n<p><b>Charan Anand:<\/b>Ci\u00f2 che ho capito di tutte le scritture che ho letto \u00e8 che parlano tutte della stessa esperienza interiore di pace in lingue diverse e con i modi espressivi della loro epoca. Prem riecheggia un antico messaggio e insegna un modo pratico per mettersi in contatto con quell\u2019esperienza. Parla di ci\u00f2 cui veramente anela il nostro cuore. Afferma: \u201cSe volete il mio aiuto per questo, io posso aiutarvi.\u201d Questo \u00e8 il suo dono.<\/p>\n<p><b>PremRawat.com:<\/b>Che cosa dici alle persone che ritengono che ci\u00f2 che offre Prem sia \u201creligioso\u201d o \u201cspirituale\u201d?<\/p>\n<p><b>Charan Anand:<\/b> Per mia esperienza, questa Conoscenza non \u00e8 n\u00e9 religiosa n\u00e9 spirituale. \u00c8 un\u2019esperienza diretta della pace interiore. Il nostro respiro \u00e8 religioso o spirituale? Sta in piedi da solo. Ad esempio, quando mangi non parli. Quando bevi, non parli. Semplicemente ti godi quell\u2019esperienza di mangiare e di bere. Lo stesso vale per questa esperienza interiore, esiste per essere goduta. \u00c8 un processo molto naturale. Prem mi ricorda delle necessit\u00e0 di base, fondamentali, della vita, tra cui il nostro bisogno di pace. Ammiro come porti freschezza e semplicit\u00e0 in questo argomento. Ci\u00f2 gli permette di raggiungere tutti i tipi di persone in tutto il mondo. Un magnifico esempio \u00e8 il discorso di Prem (di 14 minuti) a una conferenza organizzata da studenti, la <a href=\"https:\/\/www.youtube.com\/watch?v=5fei-bJudM0\">Nordic Peace Conference<\/a> di Oslo in Norvegia.<\/p>\n<p><b>PremRawat.com:<\/b>Nella tua pluriennale esperienza, qual \u00e8 stata la riserva pi\u00f9 grande che le persone hanno rispetto a ci\u00f2 che Prem offre? E cosa vorresti dire loro per rassicurare le loro eventuali preoccupazioni in merito?<\/p>\n<p><b>Charan Anand:<\/b>Molte persone leggono libri su diversi insegnamenti del passato e del presente. Vogliono paragonare Prem ad altri per ci\u00f2 che dice e per come vive. Attaccarsi a quei concetti pu\u00f2 interferire con l\u2019esperienza di una gioia autentica nella propria vita. I bambini sanno essere aperti. Si accostano alla vita in modo molto semplice. Quando sono stanchi, dormono. Allo stesso modo, quando senti il bisogno di pace interiore, la cosa migliore \u00e8 ascoltare Prem con il cuore di un bambino. S\u00ec, va bene fare domande, ma poi arriva il momento di andare oltre le domande e i concetti per provare la pace personale.<\/p>\n<blockquote>\n<p>Quando si ascolta Prem, \u00e8 bene avere un approccio semplice e sincero.<\/p>\n<\/blockquote>\n<p style=\"text-align: right;\">Charan Anand<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;20px&#8221; link_text_color=&#8221;#1565b7&#8243; custom_margin=&#8221;||50px|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p><b>PremRawat.com:<\/b>Qualche pensiero sull\u2019et\u00e0 che avanza? Qualche suggerimento per essere longevi?<\/p>\n<p><b>Charan Anand: <\/b>Invecchiare non mi preoccupa. Molto tempo fa Prem disse: \u201cQuando ci concentriamo sul corpo, sentiamo l\u2019et\u00e0. Quando ci concentriamo sul sentimento interiore, ci sentiamo senza et\u00e0.\u201d Lui mi ha mostrato ci\u00f2 che non ha et\u00e0 e a me piace concentrarmi su quello. Al tempo stesso, il mio corpo \u00e8 la mia casa e devo prendermene cura. C\u2019\u00e8 quel detto: \u201cDopo i 60 anni, se non ti svegli con qualche dolorino e rigidit\u00e0, vuol dire che sei morto.\u201d Ovviamente quando mi sveglio ho qualche dolore. Ho appena compiuto 92 anni, il 2 maggio 2023, per\u00f2 faccio del mio meglio per restare in salute. Per me \u00e8 importante. Come una casa o un\u2019auto, il corpo ha bisogno di manutenzione. Cerco di mangiare bene, di fare esercizio quotidiano e di dormire abbastanza. Ci sono molti modi di fare esercizio, devi trovare quelli che ti piacciono. A me piace giocare a golf, fare yoga, camminare all\u2019aria aperta, ascoltare musica e cantare.<\/p>\n<p>Anni addietro mi piaceva giocare a golf per tenermi in forma e organizzavo tornei di beneficenza per sostenere il Food for People Program della <a href=\"https:\/\/tprf.org\/it\/\">The Prem Rawat Foundation (TPRF)<\/a> che fornisce pasti, acqua potabile e opportunit\u00e0 di istruzione a comunit\u00e0 povere.<\/p>\n<blockquote>\n<p>So che un giorno dovr\u00f2 lasciare tutto e voglio essere in sintonia con la pace che c\u2019\u00e8 dentro di me.<\/p>\n<\/blockquote>\n<p style=\"text-align: right;\">Charan Anand<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;20px&#8221; link_text_color=&#8221;#1565b7&#8243; custom_margin=&#8221;||50px|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p>Anche praticare la Conoscenza ogni giorno \u00e8 molto importante per me. Mi porta profondamente dentro di me. Come ha insegnato Prem: \u201cDai alla Conoscenza una reale possibilit\u00e0.\u201d So che un giorno dovr\u00f2 lasciare tutto e voglio essere in sintonia con la pace che c\u2019\u00e8 dentro di me. Un giorno Shri Maharaji mi mand\u00f2 una lettera. Il suo primo consiglio era: \u201cPrenditi cura della tua salute.\u201d Poi: \u201cGoditi la pratica della Conoscenza.\u201d In terzo luogo: \u201cAscolta il mio messaggio e continua a collaborare.\u201d Sono molto grato di sentirmi in buona salute e felice. Sono molto grato a Prem per tutto ci\u00f2 che mi ha dato. Fortunatamente, posso ancora prendermi cura di me stesso. Perci\u00f2, per favore, fatelo anche voi.<\/p>\n<p><strong>PremRawat.com:<\/strong> Ti ringrazio molto, Charan Anand Ji, per tutto il tuo impegno passato e presente. La tua storia \u00e8 quella di una vita interamente dedicata alla pace interiore. La bont\u00e0 che hai dimostrato a tante persone in tutto il mondo sar\u00e0 sempre apprezzata. Charan Anand: \u00c8 stato per me un privilegio parlarvi del viaggio della mia vita, cos\u00ec pieno di felicit\u00e0. Sar\u00f2 eternamente grato a Shri Maharaji per la meravigliosa vita vissuta insieme a lui, e ora con Prem. Li porto nel mio cuore con amore profondo e il massimo rispetto.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/cdn.premrawat.com\/2023\/06\/Charan-Anand-Malibu-2017.jpg&#8221; title_text=&#8221;Charan-Anand-Malibu-2017&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||15px||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;20px&#8221; link_text_color=&#8221;#1565b7&#8243; custom_margin=&#8221;||50px|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p style=\"text-align: right;\">Charan Anand a Malibu, California \u2013 2017<\/p>\n<p>Se desideri mandare un messaggio di apprezzamento a Charan Anand, contatta: editor@premrawat.com <strong><em>Marcia Newman desidera ringraziare Larry Lefkowitz, David Shimberg, Mitch Ditkoff e Henry Reif per il loro impegno e collaborazione nella realizzazione di questa speciale intervista con Charan Anand.<\/em><\/strong><\/p>\n<p style=\"text-align: right;\"><strong><em><\/em><\/strong>Foto principale \u2013 Charan Anand parla a Montpellier, Francia &#8211; 1985<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Goditi questa intervista affascinante e di vasta portata con uno dei pi\u00f9 vecchi studenti e amici di Prem Rawat, Charan Anand.<\/p>\n","protected":false},"author":18,"featured_media":37148,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[4007,3936],"tags":[4174],"podcast-category":[],"class_list":["post-39103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conoscenza-del-se","category-reflections-it","tag-interview-it"],"acf":[],"_links":{"self":[{"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/posts\/39103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/comments?post=39103"}],"version-history":[{"count":9,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/posts\/39103\/revisions"}],"predecessor-version":[{"id":39123,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/posts\/39103\/revisions\/39123"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/media\/37148"}],"wp:attachment":[{"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/media?parent=39103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/categories?post=39103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/tags?post=39103"},{"taxonomy":"podcast-category","embeddable":true,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/podcast-category?post=39103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}