!function(e){var t={};function o(i){if(t[i])return t[i].exports;var r=t[i]={i:i,l:!1,exports:{}};return e[i].call(r.exports,r,r.exports,o),r.l=!0,r.exports}o.m=e,o.c=t,o.d=function(e,t,i){o.o(e,t)||Object.defineProperty(e,t,{enumerable:!0,get:i})},o.r=function(e){"undefined"!=typeof Symbol&&Symbol.toStringTag&&Object.defineProperty(e,Symbol.toStringTag,{value:"Module"}),Object.defineProperty(e,"__esModule",{value:!0})},o.t=function(e,t){if(1&t&&(e=o(e)),8&t)return e;if(4&t&&"object"==typeof e&&e&&e.__esModule)return e;var i=Object.create(null);if(o.r(i),Object.defineProperty(i,"default",{enumerable:!0,value:e}),2&t&&"string"!=typeof e)for(var r in e)o.d(i,r,function(t){return e[t]}.bind(null,r));return i},o.n=function(e){var t=e&&e.__esModule?function(){return e.default}:function(){return e};return o.d(t,"a",t),t},o.o=function(e,t){return Object.prototype.hasOwnProperty.call(e,t)},o.p="",o(o.s=8)}([function(e,t){e.exports=window.wp.data},function(e,t){e.exports=window.wp.element},function(e,t){e.exports=window.wp.components},function(e,t){e.exports=window.wp.i18n},function(e,t,o){"use strict";Object.defineProperty(t,"__esModule",{value:!0}),t.redirectOnSaveCompletion=void 0;var i=o(0),r=function(e){var t=(0,i.select)("core/editor").getCurrentPostAttribute("status"),o=(0,i.select)("core/editor").getEditedPostAttribute("status");"dp-rewrite-republish"===t&&"publish"===o&&(0,i.dispatch)("core/editor").editPost({status:t}),window.location.assign(e)};t.redirectOnSaveCompletion=function(e,t){var o=(0,i.select)("core/editor").isSavingPost(),n=(0,i.select)("core/editor").isAutosavingPost(),s=(0,i.select)("core/edit-post").hasMetaBoxes(),a=(0,i.select)("core/edit-post").isSavingMetaBoxes();return s&&!a&&t.wasSavingMetaboxes&&r(e),s||o||!t.wasSavingPost||t.wasAutoSavingPost||r(e),{isSavingPost:o,isSavingMetaBoxes:a,isAutosavingPost:n}}},,,,function(e,t,o){"use strict";var i=o(1),r=o(2),n=o(3),s=o(0),a=o(4);var u,l,c,p=function(){(0,s.dispatch)("core/editor").savePost();var e=!1,t=!1,o=!1;(0,s.subscribe)((function(){var i=(0,a.redirectOnSaveCompletion)(duplicatePostStrings.checkLink,{wasSavingPost:e,wasSavingMetaboxes:t,wasAutoSavingPost:o});e=i.isSavingPost,t=i.isSavingMetaBoxes,o=i.isAutosavingPost}))},d={Publish:(0,n.__)("Republish","duplicate-post"),"Publish:":(0,n.__)("Republish:","duplicate-post"),"Publish on:":(0,n.__)("Republish on:","duplicate-post"),"Are you ready to publish?":(0,n.__)("Are you ready to republish your post?","duplicate-post"),"Double-check your settings before publishing.":(0,i.createInterpolateElement)((0,n.__)("After republishing your changes will be merged into the original post and you'll be redirected there.<br /><br />Do you want to compare your changes with the original version before merging?<br /><br /><button>Save changes and compare</button>","duplicate-post"),{button:wp.element.createElement(r.Button,{isSecondary:!0,onClick:p}),br:wp.element.createElement("br",null)}),Schedule:(0,n.__)("Schedule republish","duplicate-post"),"Schedule…":(0,n.__)("Schedule republish…","duplicate-post"),"post action/button labelSchedule":(0,n.__)("Schedule republish","duplicate-post"),"Are you ready to schedule?":(0,n.__)("Are you ready to schedule the republishing of your post?","duplicate-post"),"Your work will be published at the specified date and time.":(0,i.createInterpolateElement)((0,n.__)("You're about to replace the original with this rewritten post at the specified date and time.<br /><br />Do you want to compare your changes with the original version before merging?<br /><br /><button>Save changes and compare</button>","duplicate-post"),{button:wp.element.createElement(r.Button,{isSecondary:!0,onClick:p}),br:wp.element.createElement("br",null)}),"is now scheduled. It will go live on":(0,n.__)(", the rewritten post, is now scheduled to replace the original post. It will be published on","duplicate-post")};for(var b in d)(0,n.setLocaleData)((c=[d[b],"duplicate-post"],(l=b)in(u={})?Object.defineProperty(u,l,{value:c,enumerable:!0,configurable:!0,writable:!0}):u[l]=c,u))}]);{"id":19937,"date":"2020-03-29T00:41:33","date_gmt":"2020-03-29T04:41:33","guid":{"rendered":"https:\/\/prdev.timelesstoday.io\/in-quarantena-con-prem-rawat-8-giorno-2\/"},"modified":"2023-01-13T03:03:35","modified_gmt":"2023-01-13T08:03:35","slug":"lockdown-with-prem-rawat-day-8","status":"publish","type":"post","link":"https:\/\/staging.premrawat.com\/it\/lockdown-with-prem-rawat-day-8\/","title":{"rendered":"In quarantena con Prem Rawat &#8211; 8\u00b0 giorno"},"content":{"rendered":"<p>Salve a tutti, spero che questo video vi trovi tutti bene. E di nuovo continueremo con le domande, oggi.<\/p>\n<p>Un&#8217;altra domanda \u00e8: \u201cSono in quarantena con mia moglie, mia suocera e mia figlia Laura di 8 anni. Io e Laura cerchiamo di occupare al meglio questi momenti. Io condivido con lei i tuoi pensieri, la tua guida, e a lei piace; per\u00f2 mia moglie e mia suocera sono molto impaurite e ansiose. Vorrei aiutarle ma non so come fare, mi puoi aiutare? Grazie.\u201d Questa \u00e8 una domanda che viene da Pedro.<\/p>\n<p>Buona domanda, Pedro. Perch\u00e9 penso che molte persone abbiano molta paura di questa cosa, di ci\u00f2 che accadr\u00e0. Ma non \u00e8 una cosa cos\u00ec grande. Se veramente ci pensi, devi prendere alcune precauzioni.<\/p>\n<p>Dunque, questo virus \u00e8 un virus come un comune raffreddore, da quello che ho capito. In realt\u00e0 ha dei sintomi molto lievi a meno che tu non abbia dei problemi gi\u00e0 sottostanti: allora pu\u00f2 diventare parecchio complicato. Questo \u00e8 quello che ho capito io di ci\u00f2 che ho sentito da vari e diversi dottori.<\/p>\n<p>Fondamentalmente, se tieni le mani pulite, non ti tocchi la faccia e stai lontano dalle persone che possono essere portatori di questa malattia, se non stai in un ambiente in cui loro starnutiscono, qualcosa del genere, per cui il virus potrebbe rimanere in giro per parecchio tempo, allora non hai veramente molto di cui preoccuparti.<\/p>\n<p>Dunque, se sei in quarantena, se non esci, se mantieni le distanze, se tieni le mani pulite e non ti tocchi il naso, la bocca e gli occhi, hai veramente poco da temere.<\/p>\n<p>In effetti questo pu\u00f2 essere una cosa che fa la differenza, per una persona, oppure no, ma in effetti quello che devono comprendere \u00e8 che questa \u00e8 sempre vita. L\u2019apprezzamento che possono avere per questa vita \u00e8 ancora importante. Staranno bene, se prendono le precauzioni staranno bene.<\/p>\n<p>E magari in queste circostanze specifiche le persone si confondono molto ma dovete prendere delle precauzioni anche quando attraversate la strada.<\/p>\n<p>Tante volte quando gli americani vanno in Inghilterra e guidano a sinistra invece che sulla destra \u00e8 abbastanza facile guardare dalla parte sbagliata per vedere se arrivano le macchine. Se non vedono nessuno partono e magari si trovano una macchina davanti.<\/p>\n<p>Dunque, precauzioni dobbiamo prenderne sempre. Se non prendiamo queste precauzioni non riusciamo a fare il nostro lavoro.<\/p>\n<p>Quello che dobbiamo fare dunque \u00e8 veramente questione di definire bene le priorit\u00e0. Le priorit\u00e0 non possono essere aver paura, perch\u00e9 quello che butta gi\u00f9 fisicamente, ti consuma.<\/p>\n<p>E quando accade, questo azzera le persone che sono ansiose riguardo a qualcosa, e non dormono bene. Questa \u00e8 la cosa peggiore che puoi fare per il tuo sistema immunitario. Devi dormire bene perch\u00e9 il tuo sistema immunitario sia al massimo.<\/p>\n<p>Ecco dunque la buona notizia: potete prendere delle precauzioni e questo vi impedir\u00e0 di prendere il virus. \u00c8 cos\u00ec semplice. Non c\u2019\u00e8 ragione di aver paura.<\/p>\n<p>\u201cCaro Prem, ho una domanda: per favore, cosa possiamo offrire, specialmente ai nostri figli e ai nostri nipotini, in questi momenti, separati gli uni dagli altri, a parte la bont\u00e0, l\u2019amore e l\u2019empatia?\u201d E questo viene da Barbara di Vienna.<\/p>\n<p>Ciao Barbara, buona domanda. Cosa possiamo offrire loro? Innanzitutto, la nostra famiglia, nella quale forse siamo in isolamento. Una cosa che volevo dirvi \u00e8: date a ciascuno dello spazio vitale. Date a ciascuno dello spazio, perch\u00e9 questa \u00e8 una delle cose che, se non lo facciamo, specialmente se siamo rinchiusi in una casa o in uno spazio relativamente piccolo, pu\u00f2 veramente far ammattire tutti quanti.<\/p>\n<p>Quindi, per favore, prendete la vostra bont\u00e0 e gentilezza e fatele significare qualcosa. Non soltanto \u201cS\u00ec, sar\u00f2 buono e gentile con te\u201d ma rendetele una cosa reale. Una maniera in cui potete farlo \u00e8 dare a ciascuno empatia, dare a ciascuno dello spazio e questo \u00e8 molto, molto, molto importante.<\/p>\n<p>Ma poi veramente godetevi la compagnia reciproca, invece di starvene l\u00ec a cercare di trovare errori l&#8217;uno nell&#8217;altro. Perch\u00e9 le famiglie a volte lo fanno in maniera spettacolare. Se ne stanno l\u00ec a dire: \u201cGuarda per\u00f2 non si fa mica cos\u00ec, questo \u00e8 sbagliato, e questo e quell&#8217;altro\u201d e questo fa ammattire tutti quanti.<\/p>\n<p>Invece di fare questo, date a ciascuno dello spazio; date a ciascuno del rispetto. Noi siamo cos\u00ec soliti rispettare tutti quelli che si trovano al di fuori del nostro cerchio familiare ma questo \u00e8 un buon momento per dare a ciascuno del rispetto, dare a ciascuno dello spazio, dare a ciascuno dell&#8217;empatia, dare a ciascuno della compassione, quando necessaria.<\/p>\n<p>Dare a ciascuno della comprensione e apprezzare la compagnia reciproca. Quando apprezzate qualcosa accade una cosa molto bella.<\/p>\n<p>Dovete apprezzare la compagnia reciproca perch\u00e9 di fatto vi piacete. Non lo esprimete, per\u00f2 vi piacete. Dunque \u00e8 un momento meraviglioso per farlo, quando siete in questa situazione, in una situazione di isolamento.<\/p>\n<p>\u201cLa mia domanda \u00e8: io sono su certe chat dove ci sono persone in difficolt\u00e0 e vedono tutto nero. Vorrei condividere con loro i miei pensieri, quello che penso della bellezza, per\u00f2 sono un po&#8217; preoccupato che siccome hanno una prospettiva diversa dalla mia, magari non l\u2019apprezzano. E non voglio offendere nessuno dando l\u2019impressione di prendere alla leggera la situazione attuale.<\/p>\n<p>\u201cCondivido i miei pensieri e sentimenti soltanto con quelli che conosco e che so che condividono la mia prospettiva, oppure cerco di condividerla anche con quelli che non la condividono?\u201d Questo viene da David. Non so di dove sei David, per\u00f2 \u00e8 un&#8217;ottima domanda.<\/p>\n<p>La ragione per cui una \u00e8 buona domanda \u00e8 che vuoi che gli altri sappiano le buone notizie, non \u00e8 che devi prenderla alla leggera \u00c8 una situazione seria.<\/p>\n<p>Per molte persone \u00e8 una situazione seria perch\u00e9 questo \u00e8 uno di quei virus che, sebbene faccia parte della famiglia di virus che prendiamo come un comune raffreddore, questo \u00e8 uno che non abbiamo mai sperimentato prima. Questo non ha fatto quel salto e quello non ha fatto quel salto.<\/p>\n<p>Questo non \u00e8 il momento di dare la colpa l&#8217;uno all&#8217;altro o di entrare in questo tipo di situazione ma \u00e8 il momento veramente di affrontare le cose un passo per volta.<\/p>\n<p>E la dimensione di pessimismo e oscurit\u00e0: ci sono sempre persone che vogliono dipingere quel tipo di quadro. Il suggerimento che ti darei \u00e8: prova, vedi come va; magari non avrai il 100% magari avrai il 10%, il 5% di persone che apprezzano questo messaggio, il che \u00e8 positivo.<\/p>\n<p>E sarebbe meraviglioso, perch\u00e9 questo non \u00e8 il momento di vedere tutto nero. Non c&#8217;\u00e8 proprio senso a star l\u00ec a lamentarsi. \u201cLa mia barca sta affondando la mia barca sta affondando la mia barca sta affondando.\u201d Questo non impedir\u00e0 alla barca di affondare. Fai qualcosa, per l&#8217;amor di Dio, fai qualcosa.<\/p>\n<p>E una delle cose pi\u00f9 importanti \u00e8 avere una prospettiva realistica di questa situazione, soppesarne ogni singolo elemento, non una cosa soltanto.<\/p>\n<p>Perch\u00e9 guardate, questo lo dico spesso. Mettiamo che guidi la macchina e vedi un cartello che dice: limite di velocit\u00e0 80 km all&#8217;ora, per esempio, cosa fai?<\/p>\n<p>Prendi la testa e la fissi sul tachimetro e dici: \u201cBene, questo \u00e8 il limite.\u201d Non ha parlato di un limite di andare a destra a sinistra o cose del genere o di andare a sbattere contro un&#8217;altra macchina. No, io mi limito ad assicurarmi di guidare esattamente a 80 km all&#8217;ora. Mi concentro su quello. E questo e sicuramente ti porter\u00e0 ad avere un incidente. A volte succede questo: le persone si concentrano soltanto su una cosa.<\/p>\n<p>Sapete, per esempio io mi domando sempre: ma perch\u00e9 alla gente piace guardare i film dell&#8217;orrore? Alcuni di loro sono veramente mostruosi ma a certe persone piacciono, gli piace spaventarsi. Magari \u00e8 come una paura senza pericolo ma gli piace spaventarsi.<\/p>\n<p>Dunque, forse \u00e8 un&#8217;altra cosa che sta andando in scena per le persone. Tutto questo vedere tutto nero, che questo \u00e8 terribile, che quello \u00e8 orrendo e moriremo tutti e&#8230;<\/p>\n<p>Ma il fatto \u00e8 che gli esseri umani hanno superato tante cose. Poi ci sono state epidemie di peste, ci sono state cose per cui non c&#8217;era neanche la scienza medica ad aiutare. Noi siamo in una situazione molto, molto migliore. Almeno lo possiamo comprendere, abbiamo un modo per riuscire a comprenderlo.<\/p>\n<p>Ora, tutti i governi stanno facendo quello che dovrebbero fare? Non lo credo. Ebbene, non sono qui per criticarli ma dobbiamo superare questo periodo e questo \u00e8 molto importante.<\/p>\n<p>Dunque si non si tratta di vedere tutto nero. So che ci sono delle persone\u2026 le incontro spesso. Per esempio, ti fermi a un semaforo e senti la musica, non viene dalla mia macchina, viene da un&#8217;altra macchina.<\/p>\n<p>Sicuramente a loro quella musica fa allegria e vogliono che tutto il mondo la senta; hanno abbassato i finestrini, tengono la musica a palla. Dai, ti faccio sentire questa canzone.<\/p>\n<p>Tu senti la gioia innanzitutto. Tu senti la gioia per questo messaggio bellissimo, goditelo, non vuoi essere parte del pessimismo generale. Stanne fuori.<\/p>\n<p>E se vuoi aiutare delle persone, certo, aiutale. Forse lo apprezzeranno o forse no. Se non lo apprezzano stai zitto e se lo apprezzano continua. \u00c8 semplice. Forse l\u2019ho messa in maniera troppo semplice ma spero che ti aiuti.<\/p>\n<p>Un\u2019altra domanda. \u201cLa mia domanda \u00e8: come riconoscere quando stai scivolando nell\u2019incoscienza prima che prenda piede e che tu sia spazzato via nel dramma delle emozioni? Grazie da parte di Karen.\u201d<\/p>\n<p>Ciao Karen, una grande domanda. \u00c8 una grande domanda e ti dico che questo \u00e8 relativo alla situazione che stiamo affrontando oggi. Ma \u00e8 anche molto importante nei termini di ogni giorno che viviamo.<\/p>\n<p>Dunque la domanda \u00e8: come riconosciamo il fatto di stare scivolando nell\u2019incoscienza, nell\u2019inconsapevolezza? Perch\u00e9 vai troppo in fretta, le cose accadono troppo in fretta. Rallenta. Rallenta, affronta le cose un passo per volta, \u00e8 cos\u00ec che si deve vivere.<\/p>\n<p>Proprio perch\u00e9 il mondo \u00e8 arrivato a un\u2019esagerazione, in cui vediamo quanto riesci a fare, quanto puoi essere progredito, quante cose riesci a realizzare. Guardate, ero una di quelle persone che lo sostenevano al 150%, al 200%. La realt\u00e0 \u00e8 che il 200% \u00e8 una cosa che non esiste.<\/p>\n<p>A questo punto, quello che capisco io \u00e8: prendi le cose con calma, fai un passo per volta. Che cosa stai facendo, che cosa stai per fare? Pensaci. \u00c8 questo che vuol dire essere consapevoli. Cosa sto sperimentando, cosa sento, dove sono diretto, quali sono le conseguenze di ci\u00f2 che sto per fare?<\/p>\n<p>Se si potesse fare questo, mio Dio, all&#8217;improvviso non ci sarebbe pi\u00f9 bisogno di avere le prigioni, non ci sarebbe bisogno di tutte queste armi che vengono fuori, di tutte queste cose che continuano ad accadere.<\/p>\n<p>Se le persone potessero avere questo nella loro vita, molto semplice: rallenta, prendi le cose con calma, fai le cose con gli occhi bene aperti, non con gli occhi chiusi e comprendi ci\u00f2 che stai per fare. E questi sono i modi. Perch\u00e9 quando arriva quella velocit\u00e0, \u00e8 questo che fa la velocit\u00e0: ti rende cieco a ci\u00f2 che \u00e8 ovvio, di quanto stai per fare.<\/p>\n<p>Che maniera stupenda di praticare questo, che ottima maniera di praticare questo tutti i giorni in cui sei in quarantena, perch\u00e9 ti puoi permettere di rallentare. Devi correre? Dove corri? Non c&#8217;\u00e8 ragione.<\/p>\n<p>Dunque, una grande domanda. Rallenta e guarda e valuta quello che stai facendo, valuta quello che sta accadendo. Abbi cognizione delle cose che stai per fare invece di farle prima e dopo guardarne le conseguenze. Dunque, spero che questo aiuti.<\/p>\n<p>Bene, qui c&#8217;\u00e8 un&#8217;altra domanda che ha a che vedere con le conseguenze dell&#8217;inconsapevolezza e con la tragedia: \u201c\u00c8 possibile che le dimensioni della tragedia rendano impossibile sperimentare la gioia nel momento presente? Inutile dire che mi sono trovata in fondo a una voragine. Michelle.\u201d<\/p>\n<p>Guarda, mi dispiace che ti sia trovato in una voragine. Non dovresti starci perch\u00e9, se fossi stato pi\u00f9 consapevole, avresti potuto evitarlo.<\/p>\n<p>Sai, la questione qui non \u00e8 perch\u00e9 nella vita\u2026 la questione non \u00e8 fare scomparire le cose, fare scomparire i tuoi problemi. Veramente si tratta di aggirarli, imparare l&#8217;arte di aggirarli, i tuoi problemi. Aggirare.<\/p>\n<p>Non devi guardare la montagna e dire: \u201cMah, devo attraversare la montagna\u201d, no. Trova un modo per aggirare il problema, \u00e8 cos\u00ec tanto pi\u00f9 facile e pi\u00f9 bello e pi\u00f9 fattibile. E cos\u00ec dovrebbe essere.<\/p>\n<p>Dunque, non essere incosciente, perch\u00e9 la vita non vuole che tu sia cos\u00ec, la vita vuole che tu sia molto, molto consapevole e che apprezzi ogni giorno ogni cosa che sta accadendo intorno a te.<\/p>\n<p>Non so se ho mai detto che le conseguenze dell\u2019incoscienza sono una tragedia, per\u00f2 sono d&#8217;accordo che ci va proprio molto vicino.<\/p>\n<p>E comprendete sempre una cosa: non c&#8217;\u00e8 nulla che non potete cambiare. Avete la possibilit\u00e0 di scegliere e in ogni dato momento potete sempre scendere dalla montagna e dire: \u201cVa bene, trover\u00f2 il modo di aggirare questa montagna, prover\u00f2 il modo di aggirare i miei problemi, trover\u00f2 il modo di aggirare queste questioni.\u201d<\/p>\n<p>Questa \u00e8 una scelta che potete sempre fare, potete sempre fare. E sarebbe forse uno spreco di tempo? No. In effetti potrebbe risparmiarvi moltissimo pi\u00f9 tempo di quanto pensiate.<\/p>\n<p>Dunque, spero che questo possa essere d&#8217;aiuto. Per favore, non mettetevi in una voragine, non mettetevi nei guai. Potete uscirne. Avete trovato il modo di entrarci, potete trovare il modo di uscirne. E una volta che l&#8217;hai fatto? La cosa pi\u00f9 importante \u00e8 evitare, lo evito, evitalo.<\/p>\n<p>Dunque, questo \u00e8 il tempo che abbiamo per oggi e parler\u00f2 di nuovo con voi domani. Grazie<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Salve a tutti, spero che questo video vi trovi tutti bene. E di nuovo continueremo con le domande, oggi. Un&#8217;altra domanda \u00e8: \u201cSono in quarantena con mia moglie, mia suocera e mia figlia Laura di 8 anni. Io e Laura cerchiamo di occupare al meglio questi momenti. Io condivido con lei i tuoi pensieri, la [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":2542,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[3920,3805],"tags":[],"podcast-category":[],"class_list":["post-19937","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lockdown-series-italian","category-videos-italian-it"],"acf":[],"_links":{"self":[{"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/posts\/19937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/comments?post=19937"}],"version-history":[{"count":4,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/posts\/19937\/revisions"}],"predecessor-version":[{"id":24953,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/posts\/19937\/revisions\/24953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/media\/2542"}],"wp:attachment":[{"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/media?parent=19937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/categories?post=19937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/tags?post=19937"},{"taxonomy":"podcast-category","embeddable":true,"href":"https:\/\/staging.premrawat.com\/it\/wp-json\/wp\/v2\/podcast-category?post=19937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}