!function(e){var t={};function o(i){if(t[i])return t[i].exports;var r=t[i]={i:i,l:!1,exports:{}};return e[i].call(r.exports,r,r.exports,o),r.l=!0,r.exports}o.m=e,o.c=t,o.d=function(e,t,i){o.o(e,t)||Object.defineProperty(e,t,{enumerable:!0,get:i})},o.r=function(e){"undefined"!=typeof Symbol&&Symbol.toStringTag&&Object.defineProperty(e,Symbol.toStringTag,{value:"Module"}),Object.defineProperty(e,"__esModule",{value:!0})},o.t=function(e,t){if(1&t&&(e=o(e)),8&t)return e;if(4&t&&"object"==typeof e&&e&&e.__esModule)return e;var i=Object.create(null);if(o.r(i),Object.defineProperty(i,"default",{enumerable:!0,value:e}),2&t&&"string"!=typeof e)for(var r in e)o.d(i,r,function(t){return e[t]}.bind(null,r));return i},o.n=function(e){var t=e&&e.__esModule?function(){return e.default}:function(){return e};return o.d(t,"a",t),t},o.o=function(e,t){return Object.prototype.hasOwnProperty.call(e,t)},o.p="",o(o.s=8)}([function(e,t){e.exports=window.wp.data},function(e,t){e.exports=window.wp.element},function(e,t){e.exports=window.wp.components},function(e,t){e.exports=window.wp.i18n},function(e,t,o){"use strict";Object.defineProperty(t,"__esModule",{value:!0}),t.redirectOnSaveCompletion=void 0;var i=o(0),r=function(e){var t=(0,i.select)("core/editor").getCurrentPostAttribute("status"),o=(0,i.select)("core/editor").getEditedPostAttribute("status");"dp-rewrite-republish"===t&&"publish"===o&&(0,i.dispatch)("core/editor").editPost({status:t}),window.location.assign(e)};t.redirectOnSaveCompletion=function(e,t){var o=(0,i.select)("core/editor").isSavingPost(),n=(0,i.select)("core/editor").isAutosavingPost(),s=(0,i.select)("core/edit-post").hasMetaBoxes(),a=(0,i.select)("core/edit-post").isSavingMetaBoxes();return s&&!a&&t.wasSavingMetaboxes&&r(e),s||o||!t.wasSavingPost||t.wasAutoSavingPost||r(e),{isSavingPost:o,isSavingMetaBoxes:a,isAutosavingPost:n}}},,,,function(e,t,o){"use strict";var i=o(1),r=o(2),n=o(3),s=o(0),a=o(4);var u,l,c,p=function(){(0,s.dispatch)("core/editor").savePost();var e=!1,t=!1,o=!1;(0,s.subscribe)((function(){var i=(0,a.redirectOnSaveCompletion)(duplicatePostStrings.checkLink,{wasSavingPost:e,wasSavingMetaboxes:t,wasAutoSavingPost:o});e=i.isSavingPost,t=i.isSavingMetaBoxes,o=i.isAutosavingPost}))},d={Publish:(0,n.__)("Republish","duplicate-post"),"Publish:":(0,n.__)("Republish:","duplicate-post"),"Publish on:":(0,n.__)("Republish on:","duplicate-post"),"Are you ready to publish?":(0,n.__)("Are you ready to republish your post?","duplicate-post"),"Double-check your settings before publishing.":(0,i.createInterpolateElement)((0,n.__)("After republishing your changes will be merged into the original post and you'll be redirected there.<br /><br />Do you want to compare your changes with the original version before merging?<br /><br /><button>Save changes and compare</button>","duplicate-post"),{button:wp.element.createElement(r.Button,{isSecondary:!0,onClick:p}),br:wp.element.createElement("br",null)}),Schedule:(0,n.__)("Schedule republish","duplicate-post"),"Schedule…":(0,n.__)("Schedule republish…","duplicate-post"),"post action/button labelSchedule":(0,n.__)("Schedule republish","duplicate-post"),"Are you ready to schedule?":(0,n.__)("Are you ready to schedule the republishing of your post?","duplicate-post"),"Your work will be published at the specified date and time.":(0,i.createInterpolateElement)((0,n.__)("You're about to replace the original with this rewritten post at the specified date and time.<br /><br />Do you want to compare your changes with the original version before merging?<br /><br /><button>Save changes and compare</button>","duplicate-post"),{button:wp.element.createElement(r.Button,{isSecondary:!0,onClick:p}),br:wp.element.createElement("br",null)}),"is now scheduled. It will go live on":(0,n.__)(", the rewritten post, is now scheduled to replace the original post. It will be published on","duplicate-post")};for(var b in d)(0,n.setLocaleData)((c=[d[b],"duplicate-post"],(l=b)in(u={})?Object.defineProperty(u,l,{value:c,enumerable:!0,configurable:!0,writable:!0}):u[l]=c,u))}]);{"id":49804,"date":"2024-09-30T15:40:11","date_gmt":"2024-09-30T19:40:11","guid":{"rendered":"https:\/\/www.premrawat.com\/prem-rawat-et-le-conteur\/"},"modified":"2024-10-16T06:12:17","modified_gmt":"2024-10-16T10:12:17","slug":"prem-rawat-et-le-conte","status":"publish","type":"post","link":"https:\/\/staging.premrawat.com\/fr\/prem-rawat-et-le-conte\/","title":{"rendered":"Prem Rawat et le conte"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.21.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb-25px|auto||auto|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.19.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||15px||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<blockquote>\n<h3 style=\"text-align: center;\">Une histoire est un moyen d\u2019exprimer quelque chose qui ne peut \u00eatre dit autrement.<\/h3>\n<\/blockquote>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb-40px||50px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|15px|||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\"><em>\u2013 Flannery O\u2019Connor<\/em><\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb text_line_height=\u00a0\u00bb1.4em\u00a0\u00bb link_text_color=\u00a0\u00bb#1565b7&Prime; custom_margin=\u00a0\u00bb-20px||19px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p>Dans les 60 secondes qui viennent de s\u2019\u00e9couler, plus de quatre millions de courriels et 60 millions de messages WhatsApp ont \u00e9t\u00e9 envoy\u00e9s. Google a effectu\u00e9 plus de 99 000 recherches. 500 heures de vid\u00e9os YouTube et 240 000 photos sur Facebook ont \u00e9t\u00e9 t\u00e9l\u00e9charg\u00e9es. 2,4 millions de vid\u00e9os Tik Tok ont \u00e9t\u00e9 vues et plus de 350 000 tweets g\u00e9n\u00e9r\u00e9s.<\/p>\n<p>Une personne moyenne consomme pr\u00e8s de 74 gigabytes d\u2019information par jour. Cela \u00e9quivaut \u00e0 regarder 16 films par jour. 90% de toutes les donn\u00e9es dans le monde ont \u00e9t\u00e9 g\u00e9n\u00e9r\u00e9es dans les deux derni\u00e8res ann\u00e9es. Pas \u00e9tonnant que notre capacit\u00e9 d\u2019attention se soit r\u00e9duite de 8-12 secondes !<\/p>\n<p>Au milieu de cette surcharge d&rsquo;informations, les \u00eatres humains avis\u00e9s qui s&rsquo;engagent \u00e0 d\u00e9livrer un message significatif et m\u00e9morable s&rsquo;appuient de plus en plus sur une m\u00e9thode ancestrale pour se frayer un chemin dans le bruit : la narration.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/staging.premrawat.com\/wp-content\/uploads\/2024\/09\/Young-Man-Reading-Book-1200.jpg\" width=\"1200\" height=\"673\" alt=\"Toung Mar Reading a Book - Prem Rawat as storyteller\" class=\"wp-image-49427 alignnone size-full\" srcset=\"https:\/\/staging.premrawat.com\/wp-content\/uploads\/2024\/09\/Young-Man-Reading-Book-1200.jpg 1200w, https:\/\/staging.premrawat.com\/wp-content\/uploads\/2024\/09\/Young-Man-Reading-Book-1200-980x550.jpg 980w, https:\/\/staging.premrawat.com\/wp-content\/uploads\/2024\/09\/Young-Man-Reading-Book-1200-480x269.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/p>\n<p>D\u2019apr\u00e8s les neuroscientifiques :<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb text_line_height=\u00a0\u00bb1em\u00a0\u00bb custom_margin=\u00a0\u00bb30px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|||5%|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<ul>\n<li><span>Les contes ou les histoires \u00e9tablissent rapidement une relation de confiance et du lien<\/span><\/li>\n<li>Ils augmentent la r\u00e9ceptivit\u00e9 et la curiosit\u00e9.<\/li>\n<li>Ils captent l\u2019attention.<\/li>\n<li>Ils font appel aux \u00e9motions.<\/li>\n<li>Ils permettent \u00e0 l\u2019auditeur de participer au r\u00e9cit.<\/li>\n<li>Ils v\u00e9hiculent des valeurs, pas seulement des informations.<\/li>\n<li>Ils font appel \u00e0 cinq r\u00e9gions suppl\u00e9mentaires<br \/>du cerveau par rapport<\/li>\n<li>au simple r\u00e9cit des faits.<\/li>\n<li>Ils fournissent un moyen de se souvenir, d\u2019extraire et de raconter un message porteur de sens.<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb text_line_height=\u00a0\u00bb1.4em\u00a0\u00bb link_text_color=\u00a0\u00bb#1565b7&Prime; custom_margin=\u00a0\u00bb40px||19px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p><a href=\"https:\/\/staging.premrawat.com\/fr\/a-propos-de-prem-rawat\/\">Prem Rawat<\/a>, auteur \u00e0 succ\u00e8s et \u00e9ducateur \u00e0 la paix, a depuis longtemps reconnu le pouvoir du \u00ab\u00a0storytelling\u00a0\u00bb, la transmission par les histoires. Depuis qu\u2019il a commenc\u00e9 \u00e0 partager son message de paix, il y a 58 ans, citer des histoires a \u00e9t\u00e9 un de ses moyens pr\u00e9f\u00e9r\u00e9s de communication.<\/p>\n<p>En effet, l\u2019origine de l\u2019int\u00e9r\u00eat de Prem Rawat pour les contes remonte \u00e0 son enfance en Inde.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb40px||15px||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<blockquote>\n<h3 style=\"text-align: center;\">Ma famille n\u2019a eu la t\u00e9l\u00e9vision qu\u2019assez tard, et les stations de radio ne diffusaient que quelques heures par jour, mais notre maison \u00e9tait pleine de conteurs. Les histoires sous forme orale et sous forme \u00e9crite nous amusaient mais nous \u00e9duquaient aussi. Maintenant, en tant qu\u2019orateur, je transmets des histoires qui r\u00e9sonnent en moi depuis des ann\u00e9es, m\u00eame des histoires du monde entier.<\/h3>\n<\/blockquote>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_line_height=\u00a0\u00bb20px\u00a0\u00bb custom_margin=\u00a0\u00bb-35px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|15px|||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\">\u2013 Prem Rawat, Apprendre \u00e0 s\u2019\u00e9couter : Comment trouver la paix dans le bruit du monde<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb20px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<div class=\"epyt-video-wrapper\"><div  id=\"_ytid_41458\"  width=\"1080\" height=\"607\"  data-origwidth=\"1080\" data-origheight=\"607\"  data-relstop=\"1\" data-facadesrc=\"https:\/\/www.youtube.com\/embed\/KHbnvVYsNF4?enablejsapi=1&autoplay=0&cc_load_policy=0&cc_lang_pref=&iv_load_policy=1&loop=0&rel=0&fs=1&playsinline=0&autohide=2&theme=dark&color=red&controls=1&disablekb=0&\" class=\"__youtube_prefs__ epyt-facade no-lazyload\" data-epautoplay=\"1\" ><img decoding=\"async\" data-spai-excluded=\"true\" class=\"epyt-facade-poster skip-lazy\" loading=\"lazy\"  alt=\"YouTube player\"  src=\"https:\/\/i.ytimg.com\/vi\/KHbnvVYsNF4\/maxresdefault.jpg\"  \/><button class=\"epyt-facade-play\" aria-label=\"Play\"><svg data-no-lazy=\"1\" height=\"100%\" version=\"1.1\" viewBox=\"0 0 68 48\" width=\"100%\"><path class=\"ytp-large-play-button-bg\" d=\"M66.52,7.74c-0.78-2.93-2.49-5.41-5.42-6.19C55.79,.13,34,0,34,0S12.21,.13,6.9,1.55 C3.97,2.33,2.27,4.81,1.48,7.74C0.06,13.05,0,24,0,24s0.06,10.95,1.48,16.26c0.78,2.93,2.49,5.41,5.42,6.19 C12.21,47.87,34,48,34,48s21.79-0.13,27.1-1.55c2.93-0.78,4.64-3.26,5.42-6.19C67.94,34.95,68,24,68,24S67.94,13.05,66.52,7.74z\" fill=\"#f00\"><\/path><path d=\"M 45,24 27,14 27,34\" fill=\"#fff\"><\/path><\/svg><\/button><\/div><\/div>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb text_line_height=\u00a0\u00bb1.4em\u00a0\u00bb link_text_color=\u00a0\u00bb#1565b7&Prime; custom_margin=\u00a0\u00bb50px||50px||true|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p>En termes simples, une bonne histoire, comme un bon parfum, est \u00e9vocatrice. Elle attire l&rsquo;attention, entra\u00eene l&rsquo;auditeur ou le lecteur dans un nouvel \u00e9tat de conscience, l&rsquo;\u00e9l\u00e8ve, lui apprend quelque chose et, souvent, modifie son comportement.<\/p>\n<p>Comme un isotope radioactif, une bonne histoire rayonne de l&rsquo;int\u00e9rieur vers l\u2019ext\u00e9rieur, son impact allant bien au-del\u00e0 de l&rsquo;intrigue, du cadre et des personnages. En effet, la v\u00e9ritable valeur d&rsquo;une histoire r\u00e9side dans le domaine de la d\u00e9couverte, l&rsquo;exp\u00e9rience que vit la personne qui re\u00e7oit le message lorsqu&rsquo;elle acc\u00e8de \u00e0 un niveau plus profond de connaissance, de compr\u00e9hension et de sagesse, c&rsquo;est-\u00e0-dire <em>qu&rsquo;elle va au c\u0153ur de la question.<\/em><\/p>\n<p>En fin de compte, la t\u00e2che du conteur avis\u00e9 est \u00e0 la fois un d\u00e9fi et une source d&rsquo;inspiration, ce que Prem Rawat a appel\u00e9 un jour \u00ab\u00a0<em>cr\u00e9er une sc\u00e8ne sur laquelle le c\u0153ur peut danser<\/em>\u00a0\u00bb.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb40px||15px||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<blockquote>\n<h3 style=\"text-align: center;\">Racontez-moi les faits et j\u2019apprendrai. Racontez-moi la v\u00e9rit\u00e9 et je croirai. Mais racontez-moi une histoire et elle vivra pour toujours dans mon c\u0153ur.<\/h3>\n<\/blockquote>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_line_height=\u00a0\u00bb20px\u00a0\u00bb custom_margin=\u00a0\u00bb-35px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|15px|||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\">\u2013 Proverbe am\u00e9rindien<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb25px||25px||true|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<div class=\"epyt-video-wrapper\"><div  id=\"_ytid_21111\"  width=\"1080\" height=\"607\"  data-origwidth=\"1080\" data-origheight=\"607\"  data-relstop=\"1\" data-facadesrc=\"https:\/\/www.youtube.com\/embed\/enQtzU1S2iU?enablejsapi=1&autoplay=0&cc_load_policy=0&cc_lang_pref=&iv_load_policy=1&loop=0&rel=0&fs=1&playsinline=0&autohide=2&theme=dark&color=red&controls=1&disablekb=0&\" class=\"__youtube_prefs__ epyt-facade no-lazyload\" data-epautoplay=\"1\" ><img decoding=\"async\" data-spai-excluded=\"true\" class=\"epyt-facade-poster skip-lazy\" loading=\"lazy\"  alt=\"YouTube player\"  src=\"https:\/\/i.ytimg.com\/vi\/enQtzU1S2iU\/maxresdefault.jpg\"  \/><button class=\"epyt-facade-play\" aria-label=\"Play\"><svg data-no-lazy=\"1\" height=\"100%\" version=\"1.1\" viewBox=\"0 0 68 48\" width=\"100%\"><path class=\"ytp-large-play-button-bg\" d=\"M66.52,7.74c-0.78-2.93-2.49-5.41-5.42-6.19C55.79,.13,34,0,34,0S12.21,.13,6.9,1.55 C3.97,2.33,2.27,4.81,1.48,7.74C0.06,13.05,0,24,0,24s0.06,10.95,1.48,16.26c0.78,2.93,2.49,5.41,5.42,6.19 C12.21,47.87,34,48,34,48s21.79-0.13,27.1-1.55c2.93-0.78,4.64-3.26,5.42-6.19C67.94,34.95,68,24,68,24S67.94,13.05,66.52,7.74z\" fill=\"#f00\"><\/path><path d=\"M 45,24 27,14 27,34\" fill=\"#fff\"><\/path><\/svg><\/button><\/div><\/div>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb text_line_height=\u00a0\u00bb1.4em\u00a0\u00bb link_text_color=\u00a0\u00bb#1565b7&Prime; custom_margin=\u00a0\u00bb50px||-20px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p>Si vous avez des doutes sur le pouvoir de la narration, consid\u00e9rez ceci\u00a0: la plupart des traditions de grande sagesse du monde privil\u00e9gient les histoires comme moyen pour transmettre des enseignements intemporels.<\/p>\n<p>Entre 50 et 60 % de la Bible est compos\u00e9e d\u2019histoires. La Torah \u00e9galement est compos\u00e9e de 50 \u00e0 60 % d\u2019histoires. La Tripitaka des Bouddhistes (le Pali Canon) est faite de 30 \u00e0 40 % d\u2019histoires. Le Coran\u00a0? 20 \u00e0 30 %. Et un des livres les plus sacr\u00e9s en Inde, le Mahabharata, c\u2019est 100 % d\u2019histoires.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb50px||15px||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<blockquote>\n<h3 style=\"text-align: center;\">Les histoires de Prem Rawat ont le pouvoir de transformer quelque chose de tr\u00e8s complexe en un message tr\u00e8s simple qui peut \u00eatre compris facilement.<\/h3>\n<\/blockquote>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb-35px||35px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|15px|||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\"><em>&#8211; Uma JL<\/em><\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb text_line_height=\u00a0\u00bb1.4em\u00a0\u00bb link_text_color=\u00a0\u00bb#1565b7&Prime; custom_margin=\u00a0\u00bb50px||30px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p>Plus r\u00e9cemment, le livre de Prem Rawat paru en 2021, <a href=\"https:\/\/apprendreasecouterlivre.fr\/\">Apprendre \u00e0 s\u2019\u00e9couter : Comment trouver la paix dans le bruit du monde<\/a> s&rsquo;inscrit dans cette grande tradition. Ce livre \u00e0 succ\u00e8s, maintenant traduit en 16 langues, comprend 64 histoires.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||50px||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<div class=\"epyt-video-wrapper\"><div  id=\"_ytid_57709\"  width=\"1080\" height=\"607\"  data-origwidth=\"1080\" data-origheight=\"607\"  data-relstop=\"1\" data-facadesrc=\"https:\/\/www.youtube.com\/embed\/3X4FzZW3v_A?enablejsapi=1&autoplay=0&cc_load_policy=0&cc_lang_pref=&iv_load_policy=1&loop=0&rel=0&fs=1&playsinline=0&autohide=2&theme=dark&color=red&controls=1&disablekb=0&\" class=\"__youtube_prefs__ epyt-facade no-lazyload\" data-epautoplay=\"1\" ><img decoding=\"async\" data-spai-excluded=\"true\" class=\"epyt-facade-poster skip-lazy\" loading=\"lazy\"  alt=\"YouTube player\"  src=\"https:\/\/i.ytimg.com\/vi\/3X4FzZW3v_A\/maxresdefault.jpg\"  \/><button class=\"epyt-facade-play\" aria-label=\"Play\"><svg data-no-lazy=\"1\" height=\"100%\" version=\"1.1\" viewBox=\"0 0 68 48\" width=\"100%\"><path class=\"ytp-large-play-button-bg\" d=\"M66.52,7.74c-0.78-2.93-2.49-5.41-5.42-6.19C55.79,.13,34,0,34,0S12.21,.13,6.9,1.55 C3.97,2.33,2.27,4.81,1.48,7.74C0.06,13.05,0,24,0,24s0.06,10.95,1.48,16.26c0.78,2.93,2.49,5.41,5.42,6.19 C12.21,47.87,34,48,34,48s21.79-0.13,27.1-1.55c2.93-0.78,4.64-3.26,5.42-6.19C67.94,34.95,68,24,68,24S67.94,13.05,66.52,7.74z\" fill=\"#f00\"><\/path><path d=\"M 45,24 27,14 27,34\" fill=\"#fff\"><\/path><\/svg><\/button><\/div><\/div>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb text_line_height=\u00a0\u00bb1.4em\u00a0\u00bb link_text_color=\u00a0\u00bb#1565b7&Prime; custom_margin=\u00a0\u00bb50px||30px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p>En conclusion, la narration est la forme la plus ancienne et la plus puissante dans la communication entre humains, qui date d\u2019environ 100\u00a0000 ans. Dans le temps, elle existait dans les grottes orn\u00e9es, puis, avec l\u2019invention de l\u2019\u00e9criture il y a 5\u00a0000 ans, elle a pris la forme d\u2019histoires \u00e9crites.<\/p>\n<p>En honneur de cette tradition des \u00e9critures, voici une histoire que Prem Rawat a racont\u00e9 le 6 septembre 2022 au Centre de conf\u00e9rences d\u2019Ivory Rock (Amaroo), en Australie. C\u2019est une histoire amusante qui contient un message puissant susceptible d\u2019aider celui qui le lit \u00e0 d\u00e9passer ses peurs irrationnelles.<\/p>\n<p>[\/et_pb_text][et_pb_text content_tablet=\u00a0\u00bb<\/p>\n<h2 style=%22text-align: center;%22><strong>Le monstre sous le lit<\/strong><\/h2>\n<p class=%22drop-cap-stories%22><span style=%22font-family: Cormorant;%22>I<\/span>l \u00e9tait une fois un homme qui avait vraiment un gros probl\u00e8me. Il \u00e9tait convaincu qu\u2019il y avait des monstres sous son lit. Alors il ne pouvait donc pas dormir de la nuit. Et parce qu\u2019il ne dormait pas, sa sant\u00e9 se d\u00e9t\u00e9riora. Il devint de plus en plus malade.<\/p>\n<p>Ses amis lui conseill\u00e8rent d\u2019aller voir un psychiatre et un m\u00e9decin, mais, ni le psychiatre, ni le m\u00e9decin ne purent l\u2019\u2019aider. Rien ne marchait.<\/p>\n<p>Alors un jour, il rencontre un homme qui lui dit\u00a0: \u00ab\u00a0\u00c9coute, je connais ce Ma\u00eetre, cet homme plein de sagesse. Pourquoi ne vas-tu pas le voir\u00a0? Peut-\u00eatre il peut t\u2019aider.\u00a0\u00bb<\/p>\n<p>Alors, notre ami en manque de sommeil va voir le Ma\u00eetre.<\/p>\n<p>Quelques jours plus tard, ses amis le revoient et lui demandent\u00a0: \u00ab\u00a0Alors, comment \u00e7a s\u2019est pass\u00e9\u00a0?\u00a0\u00bb<\/p>\n<p>\u00ab\u00a0Ah, magnifique\u00a0!\u00a0\u00bb, a-t-il r\u00e9pondu. \u00ab\u00a0Le sage a r\u00e9solu tous mes probl\u00e8mes, ce que le psychiatre et le m\u00e9decin n\u2019avaient pas pu faire. Ce que personne n\u2019avait pu faire. Le sage a r\u00e9solu mon probl\u00e8me en une seule s\u00e9ance. Je dors comme un b\u00e9b\u00e9 maintenant. Ma sant\u00e9 s\u2019est incroyablement am\u00e9lior\u00e9e.\u00a0\u00bb<\/p>\n<p>\u00ab\u00a0Waouh\u00a0! il a d\u00fb prononcer quelques paroles divines\u00a0\u00bb, lui dirent ses amis.<\/p>\n<p class=%22drop-cap%22>\u00ab\u00a0Non, il m\u2019a simplement dit de couper les pieds de mon lit, ce que j\u2019ai fait. Maintenant, je suis s\u00fbr qu\u2019il n\u2019y a plus de monstres sous mon lit.\u00a0\u00bb<\/p>\n<p>\u00a0\u00bb content_phone=\u00a0\u00bb<\/p>\n<h2 style=%22text-align: center;%22><strong>Le monstre sous le lit<\/strong><\/h2>\n<p class=%22drop-cap-stories%22><span style=%22font-family: Cormorant;%22>I<\/span>l \u00e9tait une fois un homme qui avait vraiment un gros probl\u00e8me. Il \u00e9tait convaincu qu\u2019il y avait des monstres sous son lit. Alors il ne pouvait donc pas dormir de la nuit. Et parce qu\u2019il ne dormait pas, sa sant\u00e9 se d\u00e9t\u00e9riora. Il devint de plus en plus malade.<\/p>\n<p>Ses amis lui conseill\u00e8rent d\u2019aller voir un psychiatre et un m\u00e9decin, mais, ni le psychiatre, ni le m\u00e9decin ne purent l\u2019\u2019aider. Rien ne marchait.<\/p>\n<p>Alors un jour, il rencontre un homme qui lui dit\u00a0: \u00ab\u00a0\u00c9coute, je connais ce Ma\u00eetre, cet homme plein de sagesse. Pourquoi ne vas-tu pas le voir\u00a0? Peut-\u00eatre il peut t\u2019aider.\u00a0\u00bb<\/p>\n<p>Alors, notre ami en manque de sommeil va voir le Ma\u00eetre.<\/p>\n<p>Quelques jours plus tard, ses amis le revoient et lui demandent\u00a0: \u00ab\u00a0Alors, comment \u00e7a s\u2019est pass\u00e9\u00a0?\u00a0\u00bb<\/p>\n<p>\u00ab\u00a0Ah, magnifique\u00a0!\u00a0\u00bb, a-t-il r\u00e9pondu. \u00ab\u00a0Le sage a r\u00e9solu tous mes probl\u00e8mes, ce que le psychiatre et le m\u00e9decin n\u2019avaient pas pu faire. Ce que personne n\u2019avait pu faire. Le sage a r\u00e9solu mon probl\u00e8me en une seule s\u00e9ance. Je dors comme un b\u00e9b\u00e9 maintenant. Ma sant\u00e9 s\u2019est incroyablement am\u00e9lior\u00e9e.\u00a0\u00bb<\/p>\n<p>\u00ab\u00a0Waouh\u00a0! il a d\u00fb prononcer quelques paroles divines\u00a0\u00bb, lui dirent ses amis.<\/p>\n<p class=%22drop-cap%22>\u00ab\u00a0Non, il m\u2019a simplement dit de couper les pieds de mon lit, ce que j\u2019ai fait. Maintenant, je suis s\u00fbr qu\u2019il n\u2019y a plus de monstres sous mon lit.\u00a0\u00bb<\/p>\n<p>\u00a0\u00bb content_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb text_line_height=\u00a0\u00bb1.4em\u00a0\u00bb link_text_color=\u00a0\u00bb#1565b7&Prime; header_line_height=\u00a0\u00bb2.5em\u00a0\u00bb header_2_font_size=\u00a0\u00bb28px\u00a0\u00bb header_2_line_height=\u00a0\u00bb2em\u00a0\u00bb custom_margin=\u00a0\u00bb30px||20px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; locked=\u00a0\u00bboff\u00a0\u00bb inline_fonts=\u00a0\u00bbCormorant\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<h2 style=\"text-align: center;\"><strong>Le monstre sous le lit<\/strong><\/h2>\n<p class=\"drop-cap-stories\"><span style=\"font-family: Cormorant;\">I<\/span>l \u00e9tait une fois un homme qui avait vraiment un gros probl\u00e8me. Il \u00e9tait convaincu qu\u2019il y avait des monstres sous son lit. Alors il ne pouvait donc pas dormir de la nuit. Et parce qu\u2019il ne dormait pas, sa sant\u00e9 se d\u00e9t\u00e9riora. Il devint de plus en plus malade.<\/p>\n<p>Ses amis lui conseill\u00e8rent d\u2019aller voir un psychiatre et un m\u00e9decin, mais, ni le psychiatre, ni le m\u00e9decin ne purent l\u2019\u2019aider. Rien ne marchait.<\/p>\n<p>Alors un jour, il rencontre un homme qui lui dit\u00a0: \u00ab\u00a0\u00c9coute, je connais ce Ma\u00eetre, cet homme plein de sagesse. Pourquoi ne vas-tu pas le voir\u00a0? Peut-\u00eatre il peut t\u2019aider.\u00a0\u00bb<\/p>\n<p>Alors, notre ami en manque de sommeil va voir le Ma\u00eetre.<\/p>\n<p>Quelques jours plus tard, ses amis le revoient et lui demandent\u00a0: \u00ab\u00a0Alors, comment \u00e7a s\u2019est pass\u00e9\u00a0?\u00a0\u00bb<\/p>\n<p>\u00ab\u00a0Ah, magnifique\u00a0!\u00a0\u00bb, a-t-il r\u00e9pondu. \u00ab\u00a0Le sage a r\u00e9solu tous mes probl\u00e8mes, ce que le psychiatre et le m\u00e9decin n\u2019avaient pas pu faire. Ce que personne n\u2019avait pu faire. Le sage a r\u00e9solu mon probl\u00e8me en une seule s\u00e9ance. Je dors comme un b\u00e9b\u00e9 maintenant. Ma sant\u00e9 s\u2019est incroyablement am\u00e9lior\u00e9e.\u00a0\u00bb<\/p>\n<p>\u00ab\u00a0Waouh\u00a0! il a d\u00fb prononcer quelques paroles divines\u00a0\u00bb, lui dirent ses amis.<\/p>\n<p class=\"drop-cap\">\u00ab\u00a0Non, il m\u2019a simplement dit de couper les pieds de mon lit, ce que j\u2019ai fait. Maintenant, je suis s\u00fbr qu\u2019il n\u2019y a plus de monstres sous mon lit.\u00a0\u00bb<\/p>\n<p>[\/et_pb_text][et_pb_image src=\u00a0\u00bbhttps:\/\/staging.premrawat.com\/wp-content\/uploads\/2024\/09\/Prem-Rawat-storyutelle-the-monster-under-the-bed.jpg\u00a0\u00bb alt=\u00a0\u00bbPrem Rawat as Storyteller, the monster under the bed\u00a0\u00bb title_text=\u00a0\u00bbPrem-Rawat-storyutelle-the monster-under-the-bed\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb51px||55px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.27.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||30px||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<blockquote>\n<h3 style=\"text-align: center;\">Les histoires de Prem r\u00e9veillent mon sens d\u2019\u00e9merveillement d\u2019enfant.<br \/>Elles sont souvent amusantes avec une invitation \u00e0 rire de la vie et de notre humanit\u00e9.<br \/>Elles sont bienveillantes et font r\u00e9fl\u00e9chir.<br \/>Bien que certaines soient anciennes,<br \/>elles restent <span>d&rsquo;actualit\u00e9<\/span>.<\/h3>\n<\/blockquote>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_line_height=\u00a0\u00bb20px\u00a0\u00bb custom_margin=\u00a0\u00bb-35px||60px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|15px|0px||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\">Sigrid EA<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb-34px||40px||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<blockquote>\n<h3 style=\"text-align: center;\">Les histoires que Prem Rawat raconte sont instructives et divertissantes. <br \/>Je sens toujours que je passe un <br \/>bon moment tout en apprenant, sans avoir le sentiment d\u2019\u00e9couter une conf\u00e9rence ou un pr\u00eache.<\/h3>\n<\/blockquote>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_line_height=\u00a0\u00bb20px\u00a0\u00bb custom_margin=\u00a0\u00bb-35px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|15px|||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\">&#8211; Josephine Robinson<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_line_height=\u00a0\u00bb20px\u00a0\u00bb custom_margin=\u00a0\u00bb-35px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|15px|||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb text_line_height=\u00a0\u00bb0.3em\u00a0\u00bb link_text_color=\u00a0\u00bb#1565b7&Prime; custom_margin=\u00a0\u00bb50px||50px||true|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbmuseo-sans|700|||||||\u00a0\u00bb header_3_font=\u00a0\u00bb|600|||||||\u00a0\u00bb header_3_text_color=\u00a0\u00bbrgba(0,0,0,0.7)\u00a0\u00bb custom_margin=\u00a0\u00bb40px||||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<h3>Articles en relation et liens<\/h3>\n<p><span style=\"color: #1565b7;\"><a style=\"color: #1565b7;\" href=\"https:\/\/staging.premrawat.com\/tag\/livres\/\">Livres<\/a><\/span> \u00a0<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb-40px||39px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p style=\"text-align: right;\"><span style=\"font-size: small;\">\u00a0<\/span><\/p>\n<p>[\/et_pb_text][dgbc_blog_carousel type=\u00a0\u00bb3&Prime; include_categories=\u00a0\u00bb3703&Prime; offset_number=\u00a0\u00bb1&Prime; show_categories=\u00a0\u00bboff\u00a0\u00bb show_author=\u00a0\u00bboff\u00a0\u00bb show_date=\u00a0\u00bboff\u00a0\u00bb show_items_xlarge=\u00a0\u00bb3&Prime; dot_nav=\u00a0\u00bbon\u00a0\u00bb inner_container_padding=\u00a0\u00bb||||false|false\u00a0\u00bb content_margin=\u00a0\u00bb10px||||false|false\u00a0\u00bb post_content_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font_size=\u00a0\u00bb21px\u00a0\u00bb header_line_height=\u00a0\u00bb1.2em\u00a0\u00bb content_font_size=\u00a0\u00bb16px\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][\/dgbc_blog_carousel][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une histoire est un moyen d\u2019exprimer quelque chose qui ne peut \u00eatre dit autrement. \u2013 Flannery O\u2019ConnorDans les 60 secondes qui viennent de s\u2019\u00e9couler, plus de quatre millions de courriels et 60 millions de messages WhatsApp ont \u00e9t\u00e9 envoy\u00e9s. Google a effectu\u00e9 plus de 99 000 recherches. 500 heures de vid\u00e9os YouTube et 240 000 [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":45101,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[3934],"tags":[4225,4247,4349],"podcast-category":[],"class_list":["post-49804","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-livres","tag-personal-peace-fr","tag-prem-rawat-fr","tag-prem-rawat-storyteller-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/posts\/49804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/comments?post=49804"}],"version-history":[{"count":25,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/posts\/49804\/revisions"}],"predecessor-version":[{"id":50078,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/posts\/49804\/revisions\/50078"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/media\/45101"}],"wp:attachment":[{"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/media?parent=49804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/categories?post=49804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/tags?post=49804"},{"taxonomy":"podcast-category","embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/podcast-category?post=49804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}