!function(e){var t={};function o(i){if(t[i])return t[i].exports;var r=t[i]={i:i,l:!1,exports:{}};return e[i].call(r.exports,r,r.exports,o),r.l=!0,r.exports}o.m=e,o.c=t,o.d=function(e,t,i){o.o(e,t)||Object.defineProperty(e,t,{enumerable:!0,get:i})},o.r=function(e){"undefined"!=typeof Symbol&&Symbol.toStringTag&&Object.defineProperty(e,Symbol.toStringTag,{value:"Module"}),Object.defineProperty(e,"__esModule",{value:!0})},o.t=function(e,t){if(1&t&&(e=o(e)),8&t)return e;if(4&t&&"object"==typeof e&&e&&e.__esModule)return e;var i=Object.create(null);if(o.r(i),Object.defineProperty(i,"default",{enumerable:!0,value:e}),2&t&&"string"!=typeof e)for(var r in e)o.d(i,r,function(t){return e[t]}.bind(null,r));return i},o.n=function(e){var t=e&&e.__esModule?function(){return e.default}:function(){return e};return o.d(t,"a",t),t},o.o=function(e,t){return Object.prototype.hasOwnProperty.call(e,t)},o.p="",o(o.s=8)}([function(e,t){e.exports=window.wp.data},function(e,t){e.exports=window.wp.element},function(e,t){e.exports=window.wp.components},function(e,t){e.exports=window.wp.i18n},function(e,t,o){"use strict";Object.defineProperty(t,"__esModule",{value:!0}),t.redirectOnSaveCompletion=void 0;var i=o(0),r=function(e){var t=(0,i.select)("core/editor").getCurrentPostAttribute("status"),o=(0,i.select)("core/editor").getEditedPostAttribute("status");"dp-rewrite-republish"===t&&"publish"===o&&(0,i.dispatch)("core/editor").editPost({status:t}),window.location.assign(e)};t.redirectOnSaveCompletion=function(e,t){var o=(0,i.select)("core/editor").isSavingPost(),n=(0,i.select)("core/editor").isAutosavingPost(),s=(0,i.select)("core/edit-post").hasMetaBoxes(),a=(0,i.select)("core/edit-post").isSavingMetaBoxes();return s&&!a&&t.wasSavingMetaboxes&&r(e),s||o||!t.wasSavingPost||t.wasAutoSavingPost||r(e),{isSavingPost:o,isSavingMetaBoxes:a,isAutosavingPost:n}}},,,,function(e,t,o){"use strict";var i=o(1),r=o(2),n=o(3),s=o(0),a=o(4);var u,l,c,p=function(){(0,s.dispatch)("core/editor").savePost();var e=!1,t=!1,o=!1;(0,s.subscribe)((function(){var i=(0,a.redirectOnSaveCompletion)(duplicatePostStrings.checkLink,{wasSavingPost:e,wasSavingMetaboxes:t,wasAutoSavingPost:o});e=i.isSavingPost,t=i.isSavingMetaBoxes,o=i.isAutosavingPost}))},d={Publish:(0,n.__)("Republish","duplicate-post"),"Publish:":(0,n.__)("Republish:","duplicate-post"),"Publish on:":(0,n.__)("Republish on:","duplicate-post"),"Are you ready to publish?":(0,n.__)("Are you ready to republish your post?","duplicate-post"),"Double-check your settings before publishing.":(0,i.createInterpolateElement)((0,n.__)("After republishing your changes will be merged into the original post and you'll be redirected there.<br /><br />Do you want to compare your changes with the original version before merging?<br /><br /><button>Save changes and compare</button>","duplicate-post"),{button:wp.element.createElement(r.Button,{isSecondary:!0,onClick:p}),br:wp.element.createElement("br",null)}),Schedule:(0,n.__)("Schedule republish","duplicate-post"),"Schedule…":(0,n.__)("Schedule republish…","duplicate-post"),"post action/button labelSchedule":(0,n.__)("Schedule republish","duplicate-post"),"Are you ready to schedule?":(0,n.__)("Are you ready to schedule the republishing of your post?","duplicate-post"),"Your work will be published at the specified date and time.":(0,i.createInterpolateElement)((0,n.__)("You're about to replace the original with this rewritten post at the specified date and time.<br /><br />Do you want to compare your changes with the original version before merging?<br /><br /><button>Save changes and compare</button>","duplicate-post"),{button:wp.element.createElement(r.Button,{isSecondary:!0,onClick:p}),br:wp.element.createElement("br",null)}),"is now scheduled. It will go live on":(0,n.__)(", the rewritten post, is now scheduled to replace the original post. It will be published on","duplicate-post")};for(var b in d)(0,n.setLocaleData)((c=[d[b],"duplicate-post"],(l=b)in(u={})?Object.defineProperty(u,l,{value:c,enumerable:!0,configurable:!0,writable:!0}):u[l]=c,u))}]);{"id":46117,"date":"2024-04-17T03:17:52","date_gmt":"2024-04-17T07:17:52","guid":{"rendered":"https:\/\/www.premrawat.com\/prem-rawat-une-decennie-dans-les-medias\/"},"modified":"2024-04-29T09:55:19","modified_gmt":"2024-04-29T13:55:19","slug":"prem-rawat-une-decennie-dans-les-medias","status":"publish","type":"post","link":"https:\/\/staging.premrawat.com\/fr\/prem-rawat-une-decennie-dans-les-medias\/","title":{"rendered":"Prem Rawat : une d\u00e9cennie dans les m\u00e9dias"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.21.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.19.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb2px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.19.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.24.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb50px||50px||true|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<blockquote>\n<h3 style=\"text-align: center;\"><em>Prem Rawat est l&rsquo;un des orateurs les plus renomm\u00e9s dans le monde, et vous n&rsquo;avez peut-\u00eatre jamais entendu parler de lui.<\/em><\/h3>\n<\/blockquote>\n<p style=\"text-align: right;\"><span style=\"font-size: small;\">\u2013 Sara Sidner, CNN<br \/><\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.24.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb text_line_height=\u00a0\u00bb1.4em\u00a0\u00bb link_text_color=\u00a0\u00bb#1565b7&Prime; custom_margin=\u00a0\u00bb30px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p>Prem Rawat est sous les projecteurs des m\u00e9dias depuis son enfance, r\u00e9pondant avec esprit et sagesse \u00e0 un grand nombre de questions pos\u00e9es par des centaines de journalistes du monde entier. Cette vid\u00e9o pr\u00e9sente une s\u00e9lection d&rsquo;extraits d&rsquo;interviews r\u00e9alis\u00e9es au cours de la derni\u00e8re d\u00e9cennie, notamment aux \u00c9tats-Unis, en Afrique du Sud, en Gr\u00e8ce, aux \u00c9mirats arabes unis, au Japon, au Sri Lanka et au Br\u00e9sil.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.24.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||||true|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<div class=\"epyt-video-wrapper\"><div  id=\"_ytid_34082\"  width=\"1080\" height=\"607\"  data-origwidth=\"1080\" data-origheight=\"607\"  data-relstop=\"1\" data-facadesrc=\"https:\/\/www.youtube.com\/embed\/OdQuPm_ZgHQ?enablejsapi=1&autoplay=0&cc_load_policy=0&cc_lang_pref=&iv_load_policy=1&loop=0&rel=0&fs=1&playsinline=0&autohide=2&theme=dark&color=red&controls=1&disablekb=0&\" class=\"__youtube_prefs__ epyt-facade no-lazyload\" data-epautoplay=\"1\" ><img decoding=\"async\" data-spai-excluded=\"true\" class=\"epyt-facade-poster skip-lazy\" loading=\"lazy\"  alt=\"YouTube player\"  src=\"https:\/\/i.ytimg.com\/vi\/OdQuPm_ZgHQ\/maxresdefault.jpg\"  \/><button class=\"epyt-facade-play\" aria-label=\"Play\"><svg data-no-lazy=\"1\" height=\"100%\" version=\"1.1\" viewBox=\"0 0 68 48\" width=\"100%\"><path class=\"ytp-large-play-button-bg\" d=\"M66.52,7.74c-0.78-2.93-2.49-5.41-5.42-6.19C55.79,.13,34,0,34,0S12.21,.13,6.9,1.55 C3.97,2.33,2.27,4.81,1.48,7.74C0.06,13.05,0,24,0,24s0.06,10.95,1.48,16.26c0.78,2.93,2.49,5.41,5.42,6.19 C12.21,47.87,34,48,34,48s21.79-0.13,27.1-1.55c2.93-0.78,4.64-3.26,5.42-6.19C67.94,34.95,68,24,68,24S67.94,13.05,66.52,7.74z\" fill=\"#f00\"><\/path><path d=\"M 45,24 27,14 27,34\" fill=\"#fff\"><\/path><\/svg><\/button><\/div><\/div>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.24.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb text_line_height=\u00a0\u00bb1.4em\u00a0\u00bb link_text_color=\u00a0\u00bb#1565b7&Prime; custom_margin=\u00a0\u00bb30px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]En r\u00e9ponse \u00e0 la question d&rsquo;un animateur de radio sud-africain : \u00ab Comment d\u00e9crivez-vous la paix ? \u00bb, Prem Rawat a r\u00e9pondu comme suit : \u00ab Au-del\u00e0 des discussions, des reproches, des d\u00e9bats politiques et tout \u00e7a, existe un ressenti qui r\u00e8gne en ma\u00eetre. Quand vous ressentez cette paix-l\u00e0 dans votre vie et que vous ne vous contentez pas seulement d\u2019en parler, alors vous \u00eates v\u00e9ritablement en paix. \u00bb[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.24.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbmuseo-sans|700|||||||\u00a0\u00bb header_3_font=\u00a0\u00bb|600|||||||\u00a0\u00bb header_3_text_color=\u00a0\u00bbrgba(0,0,0,0.7)\u00a0\u00bb custom_margin=\u00a0\u00bb30px||||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<h3>Article en relation<\/h3>\n<p><span style=\"color: #1565b7;\"><a style=\"color: #1565b7;\" href=\"https:\/\/staging.premrawat.com\/fr\/category\/la-presse\/\">La presse<\/a><\/span><\/p>\n<p>[\/et_pb_text][dgbc_blog_carousel type=\u00a0\u00bb3&Prime; include_categories=\u00a0\u00bb3704&Prime; show_categories=\u00a0\u00bboff\u00a0\u00bb show_author=\u00a0\u00bboff\u00a0\u00bb show_date=\u00a0\u00bboff\u00a0\u00bb show_items_xlarge=\u00a0\u00bb3&Prime; dot_nav=\u00a0\u00bbon\u00a0\u00bb inner_container_padding=\u00a0\u00bb||||false|false\u00a0\u00bb content_margin=\u00a0\u00bb10px||||false|false\u00a0\u00bb post_content_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font_size=\u00a0\u00bb21px\u00a0\u00bb header_line_height=\u00a0\u00bb1.2em\u00a0\u00bb content_font_size=\u00a0\u00bb16px\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][\/dgbc_blog_carousel][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prem Rawat est l&rsquo;un des orateurs les plus renomm\u00e9s dans le monde, et vous n&rsquo;avez peut-\u00eatre jamais entendu parler de lui. \u2013 Sara Sidner, CNNPrem Rawat est sous les projecteurs des m\u00e9dias depuis son enfance, r\u00e9pondant avec esprit et sagesse \u00e0 un grand nombre de questions pos\u00e9es par des centaines de journalistes du monde entier. [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":45739,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[4029],"tags":[],"podcast-category":[],"class_list":["post-46117","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-presse"],"acf":[],"_links":{"self":[{"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/posts\/46117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/comments?post=46117"}],"version-history":[{"count":4,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/posts\/46117\/revisions"}],"predecessor-version":[{"id":46295,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/posts\/46117\/revisions\/46295"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/media\/45739"}],"wp:attachment":[{"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/media?parent=46117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/categories?post=46117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/tags?post=46117"},{"taxonomy":"podcast-category","embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/podcast-category?post=46117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}