!function(e){var t={};function o(i){if(t[i])return t[i].exports;var r=t[i]={i:i,l:!1,exports:{}};return e[i].call(r.exports,r,r.exports,o),r.l=!0,r.exports}o.m=e,o.c=t,o.d=function(e,t,i){o.o(e,t)||Object.defineProperty(e,t,{enumerable:!0,get:i})},o.r=function(e){"undefined"!=typeof Symbol&&Symbol.toStringTag&&Object.defineProperty(e,Symbol.toStringTag,{value:"Module"}),Object.defineProperty(e,"__esModule",{value:!0})},o.t=function(e,t){if(1&t&&(e=o(e)),8&t)return e;if(4&t&&"object"==typeof e&&e&&e.__esModule)return e;var i=Object.create(null);if(o.r(i),Object.defineProperty(i,"default",{enumerable:!0,value:e}),2&t&&"string"!=typeof e)for(var r in e)o.d(i,r,function(t){return e[t]}.bind(null,r));return i},o.n=function(e){var t=e&&e.__esModule?function(){return e.default}:function(){return e};return o.d(t,"a",t),t},o.o=function(e,t){return Object.prototype.hasOwnProperty.call(e,t)},o.p="",o(o.s=8)}([function(e,t){e.exports=window.wp.data},function(e,t){e.exports=window.wp.element},function(e,t){e.exports=window.wp.components},function(e,t){e.exports=window.wp.i18n},function(e,t,o){"use strict";Object.defineProperty(t,"__esModule",{value:!0}),t.redirectOnSaveCompletion=void 0;var i=o(0),r=function(e){var t=(0,i.select)("core/editor").getCurrentPostAttribute("status"),o=(0,i.select)("core/editor").getEditedPostAttribute("status");"dp-rewrite-republish"===t&&"publish"===o&&(0,i.dispatch)("core/editor").editPost({status:t}),window.location.assign(e)};t.redirectOnSaveCompletion=function(e,t){var o=(0,i.select)("core/editor").isSavingPost(),n=(0,i.select)("core/editor").isAutosavingPost(),s=(0,i.select)("core/edit-post").hasMetaBoxes(),a=(0,i.select)("core/edit-post").isSavingMetaBoxes();return s&&!a&&t.wasSavingMetaboxes&&r(e),s||o||!t.wasSavingPost||t.wasAutoSavingPost||r(e),{isSavingPost:o,isSavingMetaBoxes:a,isAutosavingPost:n}}},,,,function(e,t,o){"use strict";var i=o(1),r=o(2),n=o(3),s=o(0),a=o(4);var u,l,c,p=function(){(0,s.dispatch)("core/editor").savePost();var e=!1,t=!1,o=!1;(0,s.subscribe)((function(){var i=(0,a.redirectOnSaveCompletion)(duplicatePostStrings.checkLink,{wasSavingPost:e,wasSavingMetaboxes:t,wasAutoSavingPost:o});e=i.isSavingPost,t=i.isSavingMetaBoxes,o=i.isAutosavingPost}))},d={Publish:(0,n.__)("Republish","duplicate-post"),"Publish:":(0,n.__)("Republish:","duplicate-post"),"Publish on:":(0,n.__)("Republish on:","duplicate-post"),"Are you ready to publish?":(0,n.__)("Are you ready to republish your post?","duplicate-post"),"Double-check your settings before publishing.":(0,i.createInterpolateElement)((0,n.__)("After republishing your changes will be merged into the original post and you'll be redirected there.<br /><br />Do you want to compare your changes with the original version before merging?<br /><br /><button>Save changes and compare</button>","duplicate-post"),{button:wp.element.createElement(r.Button,{isSecondary:!0,onClick:p}),br:wp.element.createElement("br",null)}),Schedule:(0,n.__)("Schedule republish","duplicate-post"),"Schedule…":(0,n.__)("Schedule republish…","duplicate-post"),"post action/button labelSchedule":(0,n.__)("Schedule republish","duplicate-post"),"Are you ready to schedule?":(0,n.__)("Are you ready to schedule the republishing of your post?","duplicate-post"),"Your work will be published at the specified date and time.":(0,i.createInterpolateElement)((0,n.__)("You're about to replace the original with this rewritten post at the specified date and time.<br /><br />Do you want to compare your changes with the original version before merging?<br /><br /><button>Save changes and compare</button>","duplicate-post"),{button:wp.element.createElement(r.Button,{isSecondary:!0,onClick:p}),br:wp.element.createElement("br",null)}),"is now scheduled. It will go live on":(0,n.__)(", the rewritten post, is now scheduled to replace the original post. It will be published on","duplicate-post")};for(var b in d)(0,n.setLocaleData)((c=[d[b],"duplicate-post"],(l=b)in(u={})?Object.defineProperty(u,l,{value:c,enumerable:!0,configurable:!0,writable:!0}):u[l]=c,u))}]);{"id":43034,"date":"2023-12-14T07:34:20","date_gmt":"2023-12-14T12:34:20","guid":{"rendered":"https:\/\/www.premrawat.com\/la-tournee-en-inde-de-prem-rawat\/"},"modified":"2023-12-30T14:38:26","modified_gmt":"2023-12-30T19:38:26","slug":"la-tournee-en-inde-de-prem-rawat","status":"publish","type":"post","link":"https:\/\/staging.premrawat.com\/fr\/la-tournee-en-inde-de-prem-rawat\/","title":{"rendered":"La tourn\u00e9e en Inde de Prem Rawat"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.21.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb2px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.19.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb text_line_height=\u00a0\u00bb1.4em\u00a0\u00bb link_text_color=\u00a0\u00bb#1565b7&Prime; custom_margin=\u00a0\u00bb30px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]Poursuivant son tour du monde en 2023 (c&rsquo;est-\u00e0-dire l&rsquo;Europe, l&rsquo;Am\u00e9rique du Nord, l&rsquo;Australie, le Canada et l&rsquo;Afrique), <a href=https:\/\/staging.premrawat.com\/fr\/a-propos-de-prem-rawat\/>Prem Rawat<\/a> a r\u00e9cemment achev\u00e9 une tourn\u00e9e tr\u00e8s appr\u00e9ci\u00e9e de 26 jours en Inde, son pays d&rsquo;origine.<\/p>\n<p>Elle a d\u00e9but\u00e9 le 8 novembre par Hans Jayanti au <a href=\"https:\/\/www.rajvidyakender.org\/about-rvk\">Raj Vidya Kender<\/a> de Delhi pour c\u00e9l\u00e9brer la naissance de son p\u00e8re. Plus de 2 000 personnes \u00e9taient pr\u00e9sentes et 8 000 autres de 76 pays, via le livestream.[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb50px||50px||true|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<blockquote>\n<h3 style=\"text-align: center;\">Ce temps dont tu disposes, quelle est sa dur\u00e9e ? Combien de temps reste-t-il ? On peut y r\u00e9fl\u00e9chir.<\/h3>\n<\/blockquote>\n<h6 style=\"text-align: right;\">\u2013 Prem Rawat, Hans Jayanti, le 8 novembre 2023<\/h6>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb text_line_height=\u00a0\u00bb1.4em\u00a0\u00bb link_text_color=\u00a0\u00bb#1565b7&Prime; custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<p>Le 16 novembre, a eu lieu une session de r\u00e9flexion Understanding More\u2122 (appel\u00e9e \u00ab Jigyasa \u00bb en hindi et qui signifie \u00ab aspiration \u00bb) \u00e0 Mirzapur. Ce rassemblement d&rsquo;une journ\u00e9e enti\u00e8re, con\u00e7u pour soutenir les personnes qui pratiquent les techniques de la <a href=\"https:\/\/staging.premrawat.com\/fr\/la-connaissance-de-soi\/\">Connaissance <\/a> enseign\u00e9es par Prem Rawat (un moyen simple de d\u00e9tourner son attention du monde ext\u00e9rieur vers la source de paix int\u00e9rieure), a \u00e9t\u00e9 suivi par plus de 5 000 personnes.<\/p>\n<p>[\/et_pb_text][et_pb_image src=\u00a0\u00bbhttps:\/\/cdn.premrawat.com\/2023\/12\/prem-rawat-indian-tour-dec-2023-4.jpg\u00a0\u00bb title_text=\u00a0\u00bbprem-rawat-indian-tour-dec-2023-4&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb50px||||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb50px||50px||true|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<blockquote>\n<h3 style=\"text-align: center;\">Passer cinq heures avec Prem lors de la session Jigyasa a \u00e9t\u00e9 magique.<br \/>\nLa fa\u00e7on dont il utilise des exemples simples pour expliquer l&rsquo;importance de la pratique de la Connaissance m&rsquo;a fait prendre conscience de l&rsquo;importance de celle-ci dans ma vie.<\/h3>\n<\/blockquote>\n<h6 style=\"text-align: right;\">\u2013 Col R K Sharan (ret.)<\/h6>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb text_line_height=\u00a0\u00bb1.4em\u00a0\u00bb link_text_color=\u00a0\u00bb#1565b7&Prime; custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]Trois jours plus tard, le 19 novembre, un \u00e9v\u00e9nement public a eu lieu \u00e0 Chandigarh. L\u00e0, Prem Rawat s&rsquo;est adress\u00e9 \u00e0 50 000 personnes et \u00e0 plus de 6 800 t\u00e9l\u00e9spectateurs en ligne. Et puis, trois jours apr\u00e8s, il a men\u00e9 le deuxi\u00e8me de sa s\u00e9rie d&rsquo;\u00e9v\u00e9nements Understanding More\u2122 (\u00ab Jigyasa \u00bb) \u00e0 Ranchi. 5 000 de ses \u00e9l\u00e8ves y ont particip\u00e9.[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb50px||50px||true|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<blockquote>\n<h3 style=\"text-align: center;\">Le mot \u00ab merci \u00bb n&rsquo;exprime pas assez ma gratitude pour tout ce que j&rsquo;ai re\u00e7u pendant les \u00e9v\u00e9nements de Jigyasa. J&rsquo;ai de nouveau fait l&rsquo;exp\u00e9rience de la clart\u00e9 qui avait \u00e9t\u00e9 brouill\u00e9e par le bruit du monde.<\/h3>\n<\/blockquote>\n<h6 style=\"text-align: right;\">\u2013 Dr Sandhya Dhar<\/h6>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb text_line_height=\u00a0\u00bb1.4em\u00a0\u00bb link_text_color=\u00a0\u00bb#1565b7&Prime; custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]Le 26 novembre, \u00e0 Gaya, \u00e0 seulement quinze km de l&rsquo;endroit o\u00f9 Bouddha aurait connu l&rsquo;illumination, Prem Rawat s&rsquo;est adress\u00e9 \u00e0 un public de 375 603 personnes, \u00e9tablissant ainsi un nouveau record du monde Guinness pour \u00ab la plus grande assistance \u00e0 une conf\u00e9rence \u00bb. Plus de 20 000 personnes originaires de 85 pays ont assist\u00e9 \u00e0 la conf\u00e9rence via le livestream.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.wopg.org\/behind-the-scenes-new-guinness-world-record-award-video\/\" target=\"_blank\" rel=\"noopener\">Behind the scenes at the Gaya New Guinness World Records event<\/a> (les coulisses du nouveau record mondial Guinness) vid\u00e9o non traduite.<\/p>\n<p>C&rsquo;\u00e9tait la <a href=\"https:\/\/staging.premrawat.com\/fr\/le-lancement-du-livre-apprendre-a-secouter-par-prem-rawat-auteur-a-succes-etablit-un-nouveau-record-mondial-du-guinness-book\/\">deuxi\u00e8me fois<\/a> que Prem Rawat \u00e9tablissait un record modial cette ann\u00e9e, le premier a eu lieu \u00e0 Lucknow, en Inde, pour \u00ab la plus grande audience \u00e0 assister \u00e0 une lecture de son  livre par un seul auteur \u00bb.[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb50px||50px||true|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<blockquote>\n<h3 style=\"text-align: center;\">L&rsquo;\u00e9v\u00e9nement de Gaya a \u00e9t\u00e9 une exp\u00e9rience \u00e9poustouflante. La conf\u00e9rence de Prem Rawat sur le th\u00e8me \u00ab Comprendre la valeur du soi \u00bb a \u00e9t\u00e9 \u00e0 la fois enrichissante et \u00e9clairante.<\/h3>\n<\/blockquote>\n<h6 style=\"text-align: right;\">\u2013 Prof (Dr.) Anuradha Parasar<\/h6>\n<p>[\/et_pb_text][et_pb_image src=\u00a0\u00bbhttps:\/\/cdn.premrawat.com\/2023\/12\/prem-rawat-indian-tour-dec-2023-3.jpg\u00a0\u00bb title_text=\u00a0\u00bbprem-rawat-indian-tour-dec-2023-3&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb text_line_height=\u00a0\u00bb1.4em\u00a0\u00bb link_text_color=\u00a0\u00bb#1565b7&Prime; custom_margin=\u00a0\u00bb50px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<p>Un grand merci \u00e0 <a href=\"https:\/\/www.wopg.org\/fr\/\">Words of Peace Global<\/a> (WOPG) pour son r\u00f4le d\u00e9terminant dans la planification, la coordination et le financement de la logistique n\u00e9cessaire au comptage des 375 603 participants \u00e0 son \u00e9v\u00e9nement de record du monde de Gaya. Il s&rsquo;agit d&rsquo;une initiative de grande envergure qui a n\u00e9cessit\u00e9 la mobilisation de centaines de b\u00e9n\u00e9voles.\u00a0<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb50px||50px||true|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<blockquote>\n<h3 style=\"text-align: center;\">Un message d\u00e9livr\u00e9 \u00e0 la fin du programme de Prem \u00e0 Delhi m\u2019a donn\u00e9 un grand coup de pouce\u00a0:<br \/>\npratiquez la connaissance de soi et ressentez cette extase.<\/h3>\n<\/blockquote>\n<h6 style=\"text-align: right;\">\u2013 Ms. Gitka<\/h6>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb text_line_height=\u00a0\u00bb1.4em\u00a0\u00bb link_text_color=\u00a0\u00bb#1565b7&Prime; custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<p>En plus de ces 5 conf\u00e9rences Prem Rawat s&rsquo;est occup\u00e9 de son programme <a href=\"https:\/\/tprf.org\/fr\/food-for-people\/\">Food For People<\/a> (des repas pour tous) \u00e0 Ranchi. Cette initiative humanitaire a \u00e9t\u00e9 mise en place par sa <a href=\"https:\/\/tprf.org\/fr\/\">fondation<\/a> en 2006 pour nourrir les enfants souffrant de malnutrition. Le 24 novembre, il a rendu visite aux responsables locaux et \u00e0 de nombreux enfants pour s&rsquo;assurer que le programme continue de r\u00e9pondre aux besoins en constante \u00e9volution de la communaut\u00e9 locale.\u00a0<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb text_line_height=\u00a0\u00bb1.4em\u00a0\u00bb link_text_color=\u00a0\u00bb#1565b7&Prime; custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<div class=\"epyt-video-wrapper\"><div  id=\"_ytid_14075\"  width=\"1080\" height=\"607\"  data-origwidth=\"1080\" data-origheight=\"607\"  data-relstop=\"1\" data-facadesrc=\"https:\/\/www.youtube.com\/embed\/mYgk62epVOQ?enablejsapi=1&autoplay=0&cc_load_policy=0&cc_lang_pref=&iv_load_policy=1&loop=0&rel=0&fs=1&playsinline=0&autohide=2&theme=dark&color=red&controls=1&disablekb=0&\" class=\"__youtube_prefs__ epyt-facade no-lazyload\" data-epautoplay=\"1\" ><img decoding=\"async\" data-spai-excluded=\"true\" class=\"epyt-facade-poster skip-lazy\" loading=\"lazy\"  alt=\"YouTube player\"  src=\"https:\/\/i.ytimg.com\/vi\/mYgk62epVOQ\/maxresdefault.jpg\"  \/><button class=\"epyt-facade-play\" aria-label=\"Play\"><svg data-no-lazy=\"1\" height=\"100%\" version=\"1.1\" viewBox=\"0 0 68 48\" width=\"100%\"><path class=\"ytp-large-play-button-bg\" d=\"M66.52,7.74c-0.78-2.93-2.49-5.41-5.42-6.19C55.79,.13,34,0,34,0S12.21,.13,6.9,1.55 C3.97,2.33,2.27,4.81,1.48,7.74C0.06,13.05,0,24,0,24s0.06,10.95,1.48,16.26c0.78,2.93,2.49,5.41,5.42,6.19 C12.21,47.87,34,48,34,48s21.79-0.13,27.1-1.55c2.93-0.78,4.64-3.26,5.42-6.19C67.94,34.95,68,24,68,24S67.94,13.05,66.52,7.74z\" fill=\"#f00\"><\/path><path d=\"M 45,24 27,14 27,34\" fill=\"#fff\"><\/path><\/svg><\/button><\/div><\/div>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb text_line_height=\u00a0\u00bb1.4em\u00a0\u00bb link_text_color=\u00a0\u00bb#1565b7&Prime; custom_margin=\u00a0\u00bb50px||50px||true|false\u00a0\u00bb custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]Prem Rawat a achev\u00e9 sa tourn\u00e9e  en Inde \u00e0 Delhi le 3 d\u00e9cembre. Il s&rsquo;est adress\u00e9 \u00e0 un public de 80 000 personnes d\u00e9sireuses d&rsquo;en savoir plus sur l&rsquo;exp\u00e9rience de la <a href=\"https:\/\/staging.premrawat.com\/fr\/la-connaissance-de-soi\/\">Connaissance<\/a> qu&rsquo;il enseigne.<br \/>\nRegardez la vid\u00e9o <a href=\"https:\/\/www.timelesstoday.tv\/231203-delhi-video\" target=\"_blank\" rel=\"noopener\">ici<\/a>[\/et_pb_text][et_pb_image src=\u00a0\u00bbhttps:\/\/cdn.premrawat.com\/2023\/12\/prem-rawat-indian-tour-dec-2023-2.jpg\u00a0\u00bb title_text=\u00a0\u00bbprem-rawat-indian-tour-dec-2023-2&Prime; _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbmuseo-sans|700|||||||\u00a0\u00bb header_3_font=\u00a0\u00bb|600|||||||\u00a0\u00bb header_3_text_color=\u00a0\u00bbrgba(0,0,0,0.7)\u00a0\u00bb custom_margin=\u00a0\u00bb40px||||false|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<h3>Liens et articles associ\u00e9s<\/h3>\n<p><span style=\"color: #1565b7;\"><a href=\"https:\/\/staging.premrawat.com\/tag\/events\/\" style=\"color: #1565b7;\">\u00c9v\u00e9nements<\/a><\/span>[\/et_pb_text][dgbc_blog_carousel type=\u00a0\u00bb3&Prime; include_categories=\u00a0\u00bb3698&Prime; offset_number=\u00a0\u00bb1&Prime; show_categories=\u00a0\u00bboff\u00a0\u00bb show_author=\u00a0\u00bboff\u00a0\u00bb show_date=\u00a0\u00bboff\u00a0\u00bb show_items_xlarge=\u00a0\u00bb3&Prime; dot_nav=\u00a0\u00bbon\u00a0\u00bb inner_container_padding=\u00a0\u00bb||||false|false\u00a0\u00bb content_margin=\u00a0\u00bb10px||||false|false\u00a0\u00bb post_content_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font_size=\u00a0\u00bb21px\u00a0\u00bb header_line_height=\u00a0\u00bb1.2em\u00a0\u00bb content_font_size=\u00a0\u00bb16px\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][\/dgbc_blog_carousel][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Poursuivant sa tourn\u00e9e mondiale 2023 (c&rsquo;est-\u00e0-dire Europe, Am\u00e9rique du Nord, Australie, Canada et Afrique), Prem Rawat a r\u00e9cemment compl\u00e9t\u00e9 une tr\u00e8s appr\u00e9ci\u00e9e tourn\u00e9e de 26 jours en Inde, son pays d&rsquo;origine.<\/p>\n","protected":false},"author":18,"featured_media":42841,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[3788,3930],"tags":[4248,4247,4224],"podcast-category":[],"class_list":["post-43034","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evenements","category-humanitaire","tag-indian-tour-fr","tag-prem-rawat-fr","tag-self-knowledge-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/posts\/43034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/comments?post=43034"}],"version-history":[{"count":4,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/posts\/43034\/revisions"}],"predecessor-version":[{"id":43150,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/posts\/43034\/revisions\/43150"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/media\/42841"}],"wp:attachment":[{"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/media?parent=43034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/categories?post=43034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/tags?post=43034"},{"taxonomy":"podcast-category","embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/podcast-category?post=43034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}