!function(e){var t={};function o(i){if(t[i])return t[i].exports;var r=t[i]={i:i,l:!1,exports:{}};return e[i].call(r.exports,r,r.exports,o),r.l=!0,r.exports}o.m=e,o.c=t,o.d=function(e,t,i){o.o(e,t)||Object.defineProperty(e,t,{enumerable:!0,get:i})},o.r=function(e){"undefined"!=typeof Symbol&&Symbol.toStringTag&&Object.defineProperty(e,Symbol.toStringTag,{value:"Module"}),Object.defineProperty(e,"__esModule",{value:!0})},o.t=function(e,t){if(1&t&&(e=o(e)),8&t)return e;if(4&t&&"object"==typeof e&&e&&e.__esModule)return e;var i=Object.create(null);if(o.r(i),Object.defineProperty(i,"default",{enumerable:!0,value:e}),2&t&&"string"!=typeof e)for(var r in e)o.d(i,r,function(t){return e[t]}.bind(null,r));return i},o.n=function(e){var t=e&&e.__esModule?function(){return e.default}:function(){return e};return o.d(t,"a",t),t},o.o=function(e,t){return Object.prototype.hasOwnProperty.call(e,t)},o.p="",o(o.s=8)}([function(e,t){e.exports=window.wp.data},function(e,t){e.exports=window.wp.element},function(e,t){e.exports=window.wp.components},function(e,t){e.exports=window.wp.i18n},function(e,t,o){"use strict";Object.defineProperty(t,"__esModule",{value:!0}),t.redirectOnSaveCompletion=void 0;var i=o(0),r=function(e){var t=(0,i.select)("core/editor").getCurrentPostAttribute("status"),o=(0,i.select)("core/editor").getEditedPostAttribute("status");"dp-rewrite-republish"===t&&"publish"===o&&(0,i.dispatch)("core/editor").editPost({status:t}),window.location.assign(e)};t.redirectOnSaveCompletion=function(e,t){var o=(0,i.select)("core/editor").isSavingPost(),n=(0,i.select)("core/editor").isAutosavingPost(),s=(0,i.select)("core/edit-post").hasMetaBoxes(),a=(0,i.select)("core/edit-post").isSavingMetaBoxes();return s&&!a&&t.wasSavingMetaboxes&&r(e),s||o||!t.wasSavingPost||t.wasAutoSavingPost||r(e),{isSavingPost:o,isSavingMetaBoxes:a,isAutosavingPost:n}}},,,,function(e,t,o){"use strict";var i=o(1),r=o(2),n=o(3),s=o(0),a=o(4);var u,l,c,p=function(){(0,s.dispatch)("core/editor").savePost();var e=!1,t=!1,o=!1;(0,s.subscribe)((function(){var i=(0,a.redirectOnSaveCompletion)(duplicatePostStrings.checkLink,{wasSavingPost:e,wasSavingMetaboxes:t,wasAutoSavingPost:o});e=i.isSavingPost,t=i.isSavingMetaBoxes,o=i.isAutosavingPost}))},d={Publish:(0,n.__)("Republish","duplicate-post"),"Publish:":(0,n.__)("Republish:","duplicate-post"),"Publish on:":(0,n.__)("Republish on:","duplicate-post"),"Are you ready to publish?":(0,n.__)("Are you ready to republish your post?","duplicate-post"),"Double-check your settings before publishing.":(0,i.createInterpolateElement)((0,n.__)("After republishing your changes will be merged into the original post and you'll be redirected there.<br /><br />Do you want to compare your changes with the original version before merging?<br /><br /><button>Save changes and compare</button>","duplicate-post"),{button:wp.element.createElement(r.Button,{isSecondary:!0,onClick:p}),br:wp.element.createElement("br",null)}),Schedule:(0,n.__)("Schedule republish","duplicate-post"),"Schedule…":(0,n.__)("Schedule republish…","duplicate-post"),"post action/button labelSchedule":(0,n.__)("Schedule republish","duplicate-post"),"Are you ready to schedule?":(0,n.__)("Are you ready to schedule the republishing of your post?","duplicate-post"),"Your work will be published at the specified date and time.":(0,i.createInterpolateElement)((0,n.__)("You're about to replace the original with this rewritten post at the specified date and time.<br /><br />Do you want to compare your changes with the original version before merging?<br /><br /><button>Save changes and compare</button>","duplicate-post"),{button:wp.element.createElement(r.Button,{isSecondary:!0,onClick:p}),br:wp.element.createElement("br",null)}),"is now scheduled. It will go live on":(0,n.__)(", the rewritten post, is now scheduled to replace the original post. It will be published on","duplicate-post")};for(var b in d)(0,n.setLocaleData)((c=[d[b],"duplicate-post"],(l=b)in(u={})?Object.defineProperty(u,l,{value:c,enumerable:!0,configurable:!0,writable:!0}):u[l]=c,u))}]);{"id":40249,"date":"2023-08-31T10:06:00","date_gmt":"2023-08-31T14:06:00","guid":{"rendered":"https:\/\/www.premrawat.com\/la-tournee-europeenne-de-prem-rawat\/"},"modified":"2023-08-25T12:33:25","modified_gmt":"2023-08-25T16:33:25","slug":"la-tournee-europeenne-de-prem-rawat","status":"publish","type":"post","link":"https:\/\/staging.premrawat.com\/fr\/la-tournee-europeenne-de-prem-rawat\/","title":{"rendered":"La tourn\u00e9e europ\u00e9enne de Prem Rawat"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.21.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.19.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb2px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.19.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.21.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb text_line_height=\u00a0\u00bb1.4em\u00a0\u00bb link_text_color=\u00a0\u00bb#1565b7&Prime; custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb30px||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p><a href=\"https:\/\/www.wopg.org\/past-events\/\">Prem Rawat<\/a> Prem Rawat vient de terminer une tourn\u00e9e \u00e9clair de cinq semaines dans six pays europ\u00e9ens, un voyage pour aider des milliers de personnes en Italie, en Gr\u00e8ce, en Allemagne, au Danemark, en Irlande et en Angleterre \u00e0 mieux comprendre comment faire l&rsquo;exp\u00e9rience de la paix personnelle.<\/p>\n<p>La tourn\u00e9e a commenc\u00e9 avec une Session de r\u00e9flexion d\u2019Existence Intelligente \u00e0 Milan. C\u2019\u00e9tait une journ\u00e9e enti\u00e8re <em> Comprendre et plus encore <\/em>au cours de laquelle Prem Rawat a rencontr\u00e9 des personnes qui avaient d\u00e9j\u00e0 re\u00e7u les techniques de la <a href=\"https:\/\/staging.premrawat.com\/fr\/la-connaissance-de-soi\/\">Connaissance de soi<\/a>.<\/p>\n<p>Tout au long de la journ\u00e9e, il a partag\u00e9 ses id\u00e9es et son inspiration pour aider les participants \u00e0 mieux comprendre ce qu&rsquo;il faut pour appr\u00e9cier davantage son voyage dans la vie.<\/p>\n<p>En d&rsquo;autres termes, il s&rsquo;agissait d&rsquo;une journ\u00e9e permettant aux participants de se reconnecter, de se recentrer et de c\u00e9l\u00e9brer leur exp\u00e9rience de la paix personnelle. Huit cents personnes \u00e9taient pr\u00e9sentes et 1 394 autres se sont jointes \u00e0 l&rsquo;\u00e9v\u00e9nement<a href=\"https:\/\/www.timelesstoday.tv\/\"> sur TimelessToday<\/a> retransmis dans 51 pays.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.21.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb link_text_color=\u00a0\u00bb#1565b7&Prime; custom_margin=\u00a0\u00bb||50px|||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p>C&rsquo;est une exp\u00e9rience immersive, captivante, joyeuse et extr\u00eamement utile pour recentrer les gens sur les \u00e9l\u00e9ments fondamentaux qui donnent vie \u00e0 la <a href=\"https:\/\/staging.premrawat.com\/fr\/comment-la-pratique-de-la-connaissance-de-soi-a-t-elle-change-ma-vie\/\">pratique de la<strong> connaissance de soi<\/strong><\/a>. Les r\u00e9actions ont \u00e9t\u00e9 tr\u00e8s positives. Un participant a fait remarquer : \u00ab Tout m&rsquo;a sembl\u00e9 frais. L&rsquo;enthousiasme de Prem \u00e9tait si authentique et contagieux. Moi, je suis dou\u00e9 pour oublier des choses. Heureusement Prem est encore bien meilleur pour me rappeler ce qui est essentiel dans ma vie. \u00bb Des s\u00e9ances de travail \u00ab\u00a0Comprendre et plus encore\u00a0\u00bb ont ensuite eu lieu \u00e0 Wiesbaden et \u00e0 Londres, autant d&rsquo;expressions de l&rsquo;engagement de Prem Rawat \u00e0 inspirer les personnes qui pratiquent les techniques de la <a href=\"https:\/\/staging.premrawat.com\/fr\/la-connaissance-de-soi\/\">connaissance de soi<\/a> afin qu&rsquo;elles en retirent le maximum.<\/p>\n<p>[\/et_pb_text][et_pb_image src=\u00a0\u00bbhttps:\/\/cdn.premrawat.com\/2023\/08\/Understanding-More-Montage.jpg\u00a0\u00bb title_text=\u00a0\u00bbUnderstanding More Montage\u00a0\u00bb _builder_version=\u00a0\u00bb4.21.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.21.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb link_text_color=\u00a0\u00bb#1565b7&Prime; custom_margin=\u00a0\u00bb45px||45px||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<blockquote>\n<h3 style=\"text-align: center;\">Vous voulez-\u00eatre intelligent ? Regardez alors la sagesse du c\u0153ur.<\/h3>\n<\/blockquote>\n<h6 style=\"text-align: right;\">\u2013 Prem Rawat, Milan en Italie, le 24 juin 2023<\/h6>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.21.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb link_text_color=\u00a0\u00bb#1565b7&Prime; custom_margin=\u00a0\u00bb||50px|||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p>La tourn\u00e9e europ\u00e9enne de Prem Rawat lui a aussi donn\u00e9 deux occasions exceptionnelles de pr\u00e9senter son best-seller, <a href=\"https:\/\/hearyourselfbook.com\/\">\u00ab Apprendre \u00e0 s\u2019\u00e9couter : Comment trouver la paix dans le bruit du monde \u00bb<\/a>, \u00e0 Ath\u00e8nes et \u00e0 Dublin.<\/p>\n<p>L&rsquo;\u00e9v\u00e9nement d&rsquo;Ath\u00e8nes \u00e9tait particuli\u00e8rement intense, Prem Rawat citant r\u00e9guli\u00e8rement la perle de sagesse la plus m\u00e9morable de Socrate, \u00ab Connais-toi toi-m\u00eame \u00bb, peut-\u00eatre la fa\u00e7on la plus simple et la plus reconnue de d\u00e9crire l&rsquo;approche de Prem Rawat pour aider les gens \u00e0 faire l&rsquo;exp\u00e9rience de la paix personnelle.<\/p>\n<p>Deux jours plus tard, le 7 juillet, Prem Rawat s&rsquo;est entretenu avec Kostas Hardavellas, personnalit\u00e9 m\u00e9diatique de Blue Sky TV, pour un entretien de tr\u00e8s grande port\u00e9e,<a href=\"https:\/\/www.timelesstoday.tv\/230704-arena-interview\"> 32-minutes d\u2018interview<\/a> pour pr\u00e9senter le livre au public grec. Plus de 65 000 personnes ont \u00e9cout\u00e9 l&rsquo;\u00e9mission de Prem Rawat en Gr\u00e8ce.<\/p>\n<p>Et puis, le 15 juillet, il y a eu un \u00e9v\u00e9nement tr\u00e8s attendu \u00e0 Copenhague avec 430 personnes qui avaient d\u00e9j\u00e0 re\u00e7u les techniques de la connaissance de soi. Cela faisait 11 ans que Prem Rawat ne s&rsquo;\u00e9tait pas rendu au Danemark.<\/p>\n<p>L&rsquo;\u00e9v\u00e9nement organis\u00e9 le 20 juillet \u00e0 Dublin, avec 715 personnes dans la salle et 6 715 via le livestream de TimelessToday, a \u00e9galement connu un grand succ\u00e8s. En Irlande (ainsi que dans de nombreux pays du monde), \u201cHear Yourself\u201d <a href=\"https:\/\/staging.premrawat.com\/prem-rawats-hear-yourself-continues-having-global-impact\/\">continue d&rsquo;avoir un impact,<\/a> ayant atteint la quatri\u00e8me place sur la prestigieuse liste des best-sellers du Irish Times dans la cat\u00e9gorie des livres de poche\/non fiction.<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][et_pb_image src=\u00a0\u00bbhttps:\/\/cdn.premrawat.com\/2023\/08\/Dublin-Athens-Copenhagen-Guru-Puja.jpg\u00a0\u00bb title_text=\u00a0\u00bbDublin-Athens-Copenhagen-Guru Puja\u00a0\u00bb _builder_version=\u00a0\u00bb4.21.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||50px||false|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.21.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb link_text_color=\u00a0\u00bb#1565b7&Prime; custom_margin=\u00a0\u00bb||50px|||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p>Le 26 juillet, Prem Rawat s&rsquo;est rendu \u00e0 la prison de Leeds, en Angleterre, pour rencontrer des d\u00e9tenus qui participent au <a href=\"https:\/\/tprf.org\/peace-education-program\/\">Programme d\u2019\u00e9ducation pour la paix<\/a>. Ce programme aide les gens \u00e0 r\u00e9fl\u00e9chir \u00e0 leur propre humanit\u00e9 et \u00e0 leurs ressources int\u00e9rieures, telles que le choix et la dignit\u00e9. Les d\u00e9tenus de Leeds ont eu l&rsquo;occasion de poser des questions \u00e0 Prem Rawat, et plusieurs d&rsquo;entre eux ont expliqu\u00e9 comment les ateliers du programme les aidaient \u00e0 reprendre espoir, m\u00eame derri\u00e8re les barreaux.<\/p>\n<p>[\/et_pb_text][et_pb_image src=\u00a0\u00bbhttps:\/\/cdn.premrawat.com\/2023\/08\/HM-Prison-Leeds.jpg\u00a0\u00bb title_text=\u00a0\u00bbHM-Prison-Leeds\u00a0\u00bb _builder_version=\u00a0\u00bb4.21.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||50px||false|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.21.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]\u00ab Depuis le d\u00e9but de Programme d\u2019\u00e9ducation pour la paix, j&rsquo;ai commenc\u00e9 \u00e0 regarder le monde d&rsquo;une mani\u00e8re diff\u00e9rente. J&rsquo;ai toujours vu ma vie \u00e0 moiti\u00e9 vide. Aujourd&rsquo;hui, je la vois \u00e0 moiti\u00e9 pleine. Je voudrais donc vous remercier Prem Rawat, ainsi que les b\u00e9n\u00e9voles \u00bb, a d\u00e9clar\u00e9 l&rsquo;un des participants.[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.21.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb link_text_color=\u00a0\u00bb#1565b7&Prime; custom_margin=\u00a0\u00bb30px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p>Prem Rawat a achev\u00e9 sa tourn\u00e9e europ\u00e9enne de cinq semaines \u00e0 Brighton, en Angleterre, par la c\u00e9l\u00e9bration traditionnelle de Guru Puja, dont les racines remontent \u00e0 des milliers d&rsquo;ann\u00e9es en Inde. Elle est l\u2019occasion d&rsquo;exprimer sa gratitude au ma\u00eetre qui a permis de faire l&rsquo;exp\u00e9rience de la paix int\u00e9rieure.<\/p>\n<p>Quelle est la prochaine \u00e9tape pour Prem Rawat ? <a target=\"_blank\" rel=\"noopener\"> Une Session de r\u00e9flexion Comprendre et plus encore<\/a> \u00e0 Los Angeles le 13 ao\u00fbt. L&rsquo;\u00e9v\u00e9nement sera <a href=\"https:\/\/live.timelesstoday.tv\/\">retransmis<\/a> par TimelessToday.<\/p>\n<p>D\u00e8s que d&rsquo;autres dates de tourn\u00e9e en Am\u00e9rique du Nord seront programm\u00e9es, elles seront signal\u00e9es <a href=\"https:\/\/staging.premrawat.com\/fr\/conferences-et-retransmissions\/\">ici<\/a> sur PremRawat.com et aussi sur Words of Peace Global.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.21.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb link_text_color=\u00a0\u00bb#1565b7&Prime; link_line_height=\u00a0\u00bb1.6em\u00a0\u00bb custom_margin=\u00a0\u00bb||50px|||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p><a href=\"https:\/\/staging.premrawat.com\/fr\/video\/\">Video resources on PremRawat.com<\/a><br \/><a href=\"https:\/\/www.youtube.com\/premrawatofficial\">Prem Rawat\u2019s Official YouTube channel<\/a><br \/><a href=\"https:\/\/www.timelesstoday.tv\/about-subscriptions\">Subscribe to Prem Rawat\u2019s livestreams<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prem Rawat Prem Rawat vient de terminer une tourn\u00e9e \u00e9clair de cinq semaines dans six pays europ\u00e9ens, un voyage pour aider des milliers de personnes en Italie, en Gr\u00e8ce, en Allemagne, au Danemark, en Irlande et en Angleterre \u00e0 mieux comprendre comment faire l&rsquo;exp\u00e9rience de la paix personnelle. La tourn\u00e9e a commenc\u00e9 avec une Session [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":39648,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[3788,4004],"tags":[4192],"podcast-category":[],"class_list":["post-40249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evenements","category-programme-deducation-pour-la-paix","tag-inner-peace-prem-rawat-tours-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/posts\/40249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/comments?post=40249"}],"version-history":[{"count":4,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/posts\/40249\/revisions"}],"predecessor-version":[{"id":40254,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/posts\/40249\/revisions\/40254"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/media\/39648"}],"wp:attachment":[{"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/media?parent=40249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/categories?post=40249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/tags?post=40249"},{"taxonomy":"podcast-category","embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/podcast-category?post=40249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}