!function(e){var t={};function o(i){if(t[i])return t[i].exports;var r=t[i]={i:i,l:!1,exports:{}};return e[i].call(r.exports,r,r.exports,o),r.l=!0,r.exports}o.m=e,o.c=t,o.d=function(e,t,i){o.o(e,t)||Object.defineProperty(e,t,{enumerable:!0,get:i})},o.r=function(e){"undefined"!=typeof Symbol&&Symbol.toStringTag&&Object.defineProperty(e,Symbol.toStringTag,{value:"Module"}),Object.defineProperty(e,"__esModule",{value:!0})},o.t=function(e,t){if(1&t&&(e=o(e)),8&t)return e;if(4&t&&"object"==typeof e&&e&&e.__esModule)return e;var i=Object.create(null);if(o.r(i),Object.defineProperty(i,"default",{enumerable:!0,value:e}),2&t&&"string"!=typeof e)for(var r in e)o.d(i,r,function(t){return e[t]}.bind(null,r));return i},o.n=function(e){var t=e&&e.__esModule?function(){return e.default}:function(){return e};return o.d(t,"a",t),t},o.o=function(e,t){return Object.prototype.hasOwnProperty.call(e,t)},o.p="",o(o.s=8)}([function(e,t){e.exports=window.wp.data},function(e,t){e.exports=window.wp.element},function(e,t){e.exports=window.wp.components},function(e,t){e.exports=window.wp.i18n},function(e,t,o){"use strict";Object.defineProperty(t,"__esModule",{value:!0}),t.redirectOnSaveCompletion=void 0;var i=o(0),r=function(e){var t=(0,i.select)("core/editor").getCurrentPostAttribute("status"),o=(0,i.select)("core/editor").getEditedPostAttribute("status");"dp-rewrite-republish"===t&&"publish"===o&&(0,i.dispatch)("core/editor").editPost({status:t}),window.location.assign(e)};t.redirectOnSaveCompletion=function(e,t){var o=(0,i.select)("core/editor").isSavingPost(),n=(0,i.select)("core/editor").isAutosavingPost(),s=(0,i.select)("core/edit-post").hasMetaBoxes(),a=(0,i.select)("core/edit-post").isSavingMetaBoxes();return s&&!a&&t.wasSavingMetaboxes&&r(e),s||o||!t.wasSavingPost||t.wasAutoSavingPost||r(e),{isSavingPost:o,isSavingMetaBoxes:a,isAutosavingPost:n}}},,,,function(e,t,o){"use strict";var i=o(1),r=o(2),n=o(3),s=o(0),a=o(4);var u,l,c,p=function(){(0,s.dispatch)("core/editor").savePost();var e=!1,t=!1,o=!1;(0,s.subscribe)((function(){var i=(0,a.redirectOnSaveCompletion)(duplicatePostStrings.checkLink,{wasSavingPost:e,wasSavingMetaboxes:t,wasAutoSavingPost:o});e=i.isSavingPost,t=i.isSavingMetaBoxes,o=i.isAutosavingPost}))},d={Publish:(0,n.__)("Republish","duplicate-post"),"Publish:":(0,n.__)("Republish:","duplicate-post"),"Publish on:":(0,n.__)("Republish on:","duplicate-post"),"Are you ready to publish?":(0,n.__)("Are you ready to republish your post?","duplicate-post"),"Double-check your settings before publishing.":(0,i.createInterpolateElement)((0,n.__)("After republishing your changes will be merged into the original post and you'll be redirected there.<br /><br />Do you want to compare your changes with the original version before merging?<br /><br /><button>Save changes and compare</button>","duplicate-post"),{button:wp.element.createElement(r.Button,{isSecondary:!0,onClick:p}),br:wp.element.createElement("br",null)}),Schedule:(0,n.__)("Schedule republish","duplicate-post"),"Schedule…":(0,n.__)("Schedule republish…","duplicate-post"),"post action/button labelSchedule":(0,n.__)("Schedule republish","duplicate-post"),"Are you ready to schedule?":(0,n.__)("Are you ready to schedule the republishing of your post?","duplicate-post"),"Your work will be published at the specified date and time.":(0,i.createInterpolateElement)((0,n.__)("You're about to replace the original with this rewritten post at the specified date and time.<br /><br />Do you want to compare your changes with the original version before merging?<br /><br /><button>Save changes and compare</button>","duplicate-post"),{button:wp.element.createElement(r.Button,{isSecondary:!0,onClick:p}),br:wp.element.createElement("br",null)}),"is now scheduled. It will go live on":(0,n.__)(", the rewritten post, is now scheduled to replace the original post. It will be published on","duplicate-post")};for(var b in d)(0,n.setLocaleData)((c=[d[b],"duplicate-post"],(l=b)in(u={})?Object.defineProperty(u,l,{value:c,enumerable:!0,configurable:!0,writable:!0}):u[l]=c,u))}]);{"id":19791,"date":"2021-12-20T15:34:21","date_gmt":"2021-12-20T20:34:21","guid":{"rendered":"https:\/\/prdev.timelesstoday.io\/le-programme-deducation-pour-la-paix-de-tprf-continue-a-avoir-un-impact-profond-dans-le-monde\/"},"modified":"2021-12-20T15:34:21","modified_gmt":"2021-12-20T20:34:21","slug":"le-programme-deducation-pour-la-paix-de-tprf-continue-a-avoir-un-impact-profond-dans-le-monde","status":"publish","type":"post","link":"https:\/\/staging.premrawat.com\/fr\/le-programme-deducation-pour-la-paix-de-tprf-continue-a-avoir-un-impact-profond-dans-le-monde\/","title":{"rendered":"Le Programme d\u2019\u00c9ducation pour la Paix de TPRF continue \u00e0 avoir un impact profond dans le monde."},"content":{"rendered":"<p class=\"panel-title-lrg\"><em>\u00ab\u00a0Choisis la paix plut\u00f4t que le chaos. Choisis l\u2019amour plut\u00f4t que la haine.\u00a0\u00bb\u00a0<\/em>Prem Rawat<\/p>\n<p>Prem Rawat transmet un message unique de paix depuis son tr\u00e8s jeune \u00e2ge, de fa\u00e7ons tr\u00e8s vari\u00e9es\u00a0: lors de conf\u00e9rences publiques ou au travers d\u2019entretiens, aussi bien en t\u00eate-\u00e0 t\u00eate qu\u2019\u00e0 la t\u00e9l\u00e9vision (en vid\u00e9o) et \u00e0 la radio ou sur podcast (en audio), de livres et \u00a0de sites internet ainsi qu\u2019au cours d\u2019ateliers de formation. La plate-forme qui semble avoir le plus d\u2019impact est le\u00a0<a href=\"https:\/\/tprf.org\/fr\/programme-deducation-pour-la-paix\/\" target=\"_blank\" rel=\"noopener\">Programme d\u2019\u00e9ducation pour la paix<\/a>. Une s\u00e9rie innovante bas\u00e9e sur des vid\u00e9os destin\u00e9es \u00e0 aider chaque individu \u00e0 connaitre sa propre force et la paix personnelle. Lanc\u00e9 en 2012, le programme a d\u00e9j\u00e0 eu un impact positif sur plus de 200 000 personnes dans plus de 70 pays et il continue \u00e0 croitre. Il offre aux participants la possibilit\u00e9 de s\u2019interroger sur l\u2019utilisation de leurs propres ressources int\u00e9rieures, telles que le choix, l\u2019espoir et la dignit\u00e9.<\/p>\n<p>Plut\u00f4t que de d\u00e9crire ou de d\u00e9finir la paix personnelle, le Programme d\u2019\u00e9ducation pour la paix permet \u00e0 chacun d\u2019arriver \u00e0 sa propre compr\u00e9hension, centr\u00e9e sur la d\u00e9couverte de soi-m\u00eame. Il a d\u2019ailleurs \u00e9t\u00e9 d\u00e9montr\u00e9 que ce programme transforme \u00a0en profondeur des personnes de tous horizons, d\u00e9sireuses d\u2019am\u00e9liorer leur vie\u00a0: d\u00e9tenus, ex-combattants, membres de gangs, personnel militaire, officiers de police, r\u00e9sidents d\u2019hospices, \u00e9tudiants, religieuses, groupes communautaires et bien d\u2019autres encore.<\/p>\n<p>Son fondateur, Prem Rawat, l\u2019explique ainsi\u00a0: \u00ab\u00a0Le Programme d\u2019\u00e9ducation pour la paix vous met en contact avec vous-m\u00eame. \u00a0Il rend aux gens leur pouvoir et fait ressortir le meilleur de chacun. \u00bb<\/p>\n<p>Neufs ans d\u2019efforts ininterrompus ont permis au programme d\u2019\u00e9tendre sa port\u00e9e. Des besoins croissant de contenus, de formations et d\u2019autres ressources ont vu le jour.<\/p>\n<p>C\u2019est pour cela que TPRF fait appel \u00e0 vous et vous demande de contribuer, d\u2019ici le 31 d\u00e9cembre, \u00e0 la collecte de fonds, pour c\u00e9l\u00e9brer ses 20 ans d\u2019existence.<\/p>\n<p>Sachez que chaque don compte\u00a0et qu\u2019aucun montant n\u2019est trop petit.<\/p>\n<p>Cette semaine, les nouvelles vid\u00e9os de TPRF mettent en relief l\u2019impact du Programme d\u2019\u00e9ducation pour la paix<\/p>\n<p class=\"panel-title-lrg\"><a href=\"https:\/\/tprf.org\/fr\/tprf-a-20-ans\/\" target=\"_blank\" rel=\"noopener\">Cliquez ici pour faire un don et visionner les nouvelles vid\u00e9os.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0Choisis la paix plut\u00f4t que le chaos. Choisis l\u2019amour plut\u00f4t que la haine.\u00a0\u00bb\u00a0Prem Rawat Prem Rawat transmet un message unique de paix depuis son tr\u00e8s jeune \u00e2ge, de fa\u00e7ons tr\u00e8s vari\u00e9es\u00a0: lors de conf\u00e9rences publiques ou au travers d\u2019entretiens, aussi bien en t\u00eate-\u00e0 t\u00eate qu\u2019\u00e0 la t\u00e9l\u00e9vision (en vid\u00e9o) et \u00e0 la radio ou sur [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":6839,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[3930],"tags":[],"podcast-category":[],"class_list":["post-19791","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-humanitaire"],"acf":[],"_links":{"self":[{"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/posts\/19791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/comments?post=19791"}],"version-history":[{"count":0,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/posts\/19791\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/media\/6839"}],"wp:attachment":[{"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/media?parent=19791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/categories?post=19791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/tags?post=19791"},{"taxonomy":"podcast-category","embeddable":true,"href":"https:\/\/staging.premrawat.com\/fr\/wp-json\/wp\/v2\/podcast-category?post=19791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}